{"id":11748,"date":"2025-06-23T13:51:59","date_gmt":"2025-06-23T13:51:59","guid":{"rendered":"https:\/\/xenonkungen.com\/produkt\/nightshift-m95-led-positionsljus-24v-2-pack\/"},"modified":"2026-05-04T10:51:30","modified_gmt":"2026-05-04T09:51:30","slug":"luxtar-m95-led-positionsleuchte-24v-2er-pack","status":"publish","type":"product","link":"https:\/\/xenonkungen.com\/de\/produkt\/luxtar-m95-led-positionsleuchte-24v-2er-pack\/","title":{"rendered":"Luxtar M95 LED-Positionsleuchte 24V (2er-Pack)"},"content":{"rendered":"<h1>Flexible LED-Streifen f\u00fcr schwere Fahrzeuge in drei Versionen<\/h1>\n<p>Dieser LED-Streifen ist eine flexible und diskrete L\u00f6sung zur Verbesserung der Sichtbarkeit bei schwereren Fahrzeugen, wobei das Design die Gefahr von Besch\u00e4digungen minimiert.<\/p>\n<div class=\"specifications\">\n<h2>Spezifikationen:<\/h2>\n<ul>\n<li><span class=\"highlight\">Ausf\u00fchrung:<\/span> Vordere, seitliche und hintere Markierung.<\/li>\n<li><span class=\"highlight\">Die Dicke:<\/span> Nur 8 mm f\u00fcr eine diskrete Installation.<\/li>\n<li><span class=\"highlight\">Vielseitigkeit:<\/span> Ideal f\u00fcr schwerere Fahrzeuge und andere Anwendungen.<\/li>\n<li><span class=\"highlight\">Entwurf:<\/span> Modern und stilvoll, um das Aussehen des Fahrzeugs zu erg\u00e4nzen.<\/li>\n<\/ul>\n<h2>Merkmale:<\/h2>\n<ul>\n<li>Verbessert effektiv die Sichtbarkeit und Sicherheit im Stra\u00dfenverkehr.<\/li>\n<li>Minimiert die Verletzungsgefahr durch Kontakt mit Gegenst\u00e4nden.<\/li>\n<li>Einfacher und leichter Einbau in eine Vielzahl von Fahrzeugtypen.<\/li>\n<li>Verleiht dem Fahrzeug ein modernes und \u00e4sthetisch ansprechendes Aussehen.<\/li>\n<\/ul>\n<p><strong>Gut zu wissen:<\/strong><br \/>\nEnth\u00e4lt eine Polypropylendichtung zur Vermeidung von Scheuerstellen und zur D\u00e4mpfung von Vibrationen.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Seitliche Markierung f\u00fcr 24V-Fahrzeuge wie LKW, Bus, Landmaschinen usw.<\/p>","protected":false},"featured_media":11116,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_smort_price_nok":"63","_smort_price_dkk":"40","_smort_price_eur":"5.36","_smort_sale_price_nok":"","_smort_sale_price_dkk":"","_smort_sale_price_eur":"","smort_restorder":"","shipmondo_restorder":"","_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","smort_custom_pricelist_1":"","smort_custom_pricelist_2":"","smort_custom_pricelist_3":"","smort_custom_pricelist_4":"","smort_custom_pricelist_5":""},"anvandningsomrade":[166,238,2816],"bilmarken":[],"product_brand":[103],"product_cat":[2478],"product_tag":[],"class_list":{"0":"post-11748","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"anvandningsomrade-lastbil","7":"anvandningsomrade-slap","8":"anvandningsomrade-trailer","9":"product_brand-luxtar","10":"product_cat-positionsljus-slap","11":"pa_farg-amber","12":"pa_farg-red","13":"pa_farg-white","14":"pa_lampsockel-kontakt-open-wire","15":"pa_storlek-mm-95x20x8","16":"pa_volt-v-160","18":"first","19":"instock","20":"taxable","21":"shipping-taxable","22":"purchasable","23":"product-type-variable"},"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":null,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Luxtar M95 LED Positionsljus 24V (2-Pack) - Xenonkungen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xenonkungen.com\/de\/produkt\/luxtar-m95-led-positionsleuchte-24v-2er-pack\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Luxtar M95 LED Positionsljus 24V (2-Pack) - Xenonkungen\" \/>\n<meta property=\"og:description\" content=\"Sidomarkering f\u00f6r 24V fordon som Lastbil, Buss, Jordbruksmaskiner mfl.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xenonkungen.com\/de\/produkt\/luxtar-m95-led-positionsleuchte-24v-2er-pack\/\" \/>\n<meta property=\"og:site_name\" content=\"Xenonkungen\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-04T09:51:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/xenonkungen.com\/wp-content\/uploads\/2025\/06\/181609929-origpic-51cbba.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/xenonkungen.com\/produkt\/luxtar-m95-led-positionsljus-24v-2-pack\/\",\"url\":\"https:\/\/xenonkungen.com\/produkt\/luxtar-m95-led-positionsljus-24v-2-pack\/\",\"name\":\"Luxtar M95 LED Positionsljus 24V (2-Pack) - Xenonkungen\",\"isPartOf\":{\"@id\":\"https:\/\/xenonkungen.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/xenonkungen.com\/produkt\/luxtar-m95-led-positionsljus-24v-2-pack\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/xenonkungen.com\/produkt\/luxtar-m95-led-positionsljus-24v-2-pack\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/xenonkungen.com\/wp-content\/uploads\/2025\/06\/181609929-origpic-51cbba.jpg\",\"datePublished\":\"2025-06-23T13:51:59+00:00\",\"dateModified\":\"2026-05-04T09:51:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/xenonkungen.com\/produkt\/luxtar-m95-led-positionsljus-24v-2-pack\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/xenonkungen.com\/produkt\/luxtar-m95-led-positionsljus-24v-2-pack\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/xenonkungen.com\/produkt\/luxtar-m95-led-positionsljus-24v-2-pack\/#primaryimage\",\"url\":\"https:\/\/xenonkungen.com\/wp-content\/uploads\/2025\/06\/181609929-origpic-51cbba.jpg\",\"contentUrl\":\"https:\/\/xenonkungen.com\/wp-content\/uploads\/2025\/06\/181609929-origpic-51cbba.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/xenonkungen.com\/produkt\/luxtar-m95-led-positionsljus-24v-2-pack\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hem\",\"item\":\"https:\/\/xenonkungen.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/xenonkungen.com\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Luxtar M95 LED Positionsljus 24V (2-Pack)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/xenonkungen.com\/#website\",\"url\":\"https:\/\/xenonkungen.com\/\",\"name\":\"Xenonkungen\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/xenonkungen.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Luxtar M95 LED-Positionsleuchte 24V (2er-Pack) \u2013 Der Xenon-K\u00f6nig","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xenonkungen.com\/de\/produkt\/luxtar-m95-led-positionsleuchte-24v-2er-pack\/","og_locale":"de_DE","og_type":"article","og_title":"Luxtar M95 LED Positionsljus 24V (2-Pack) - Xenonkungen","og_description":"Sidomarkering f\u00f6r 24V fordon som Lastbil, Buss, Jordbruksmaskiner mfl.","og_url":"https:\/\/xenonkungen.com\/de\/produkt\/luxtar-m95-led-positionsleuchte-24v-2er-pack\/","og_site_name":"Xenonkungen","article_modified_time":"2026-05-04T09:51:30+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/xenonkungen.com\/wp-content\/uploads\/2025\/06\/181609929-origpic-51cbba.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/xenonkungen.com\/produkt\/luxtar-m95-led-positionsljus-24v-2-pack\/","url":"https:\/\/xenonkungen.com\/produkt\/luxtar-m95-led-positionsljus-24v-2-pack\/","name":"Luxtar M95 LED-Positionsleuchte 24V (2er-Pack) \u2013 Der Xenon-K\u00f6nig","isPartOf":{"@id":"https:\/\/xenonkungen.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/xenonkungen.com\/produkt\/luxtar-m95-led-positionsljus-24v-2-pack\/#primaryimage"},"image":{"@id":"https:\/\/xenonkungen.com\/produkt\/luxtar-m95-led-positionsljus-24v-2-pack\/#primaryimage"},"thumbnailUrl":"https:\/\/xenonkungen.com\/wp-content\/uploads\/2025\/06\/181609929-origpic-51cbba.jpg","datePublished":"2025-06-23T13:51:59+00:00","dateModified":"2026-05-04T09:51:30+00:00","breadcrumb":{"@id":"https:\/\/xenonkungen.com\/produkt\/luxtar-m95-led-positionsljus-24v-2-pack\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xenonkungen.com\/produkt\/luxtar-m95-led-positionsljus-24v-2-pack\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/xenonkungen.com\/produkt\/luxtar-m95-led-positionsljus-24v-2-pack\/#primaryimage","url":"https:\/\/xenonkungen.com\/wp-content\/uploads\/2025\/06\/181609929-origpic-51cbba.jpg","contentUrl":"https:\/\/xenonkungen.com\/wp-content\/uploads\/2025\/06\/181609929-origpic-51cbba.jpg","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/xenonkungen.com\/produkt\/luxtar-m95-led-positionsljus-24v-2-pack\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hem","item":"https:\/\/xenonkungen.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/xenonkungen.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Luxtar M95 LED Positionsljus 24V (2-Pack)"}]},{"@type":"WebSite","@id":"https:\/\/xenonkungen.com\/#website","url":"https:\/\/xenonkungen.com\/","name":"Xenonkungen","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xenonkungen.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"taxonomy_info":{"anvandningsomrade":[{"value":166,"label":"Lastbil"},{"value":238,"label":"SL\u00c4P"},{"value":2816,"label":"TRAILER"}],"product_brand":[{"value":103,"label":"LUXTAR"}],"product_cat":[{"value":2478,"label":"Positionsljus"}],"pa_farg":[{"value":2244,"label":"Amber"},{"value":2681,"label":"Red"},{"value":2296,"label":"White"}],"pa_lampsockel-kontakt":[{"value":324,"label":"Open Wire"}],"pa_storlek-mm":[{"value":2427,"label":"95x20x8"}],"pa_volt-v":[{"value":160,"label":"24"}]},"featured_image_src_large":["https:\/\/xenonkungen.com\/wp-content\/uploads\/2025\/06\/181609929-origpic-51cbba.jpg",1000,1000,false],"author_info":[],"comment_info":0,"_links":{"self":[{"href":"https:\/\/xenonkungen.com\/de\/wp-json\/wp\/v2\/product\/11748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xenonkungen.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/xenonkungen.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/xenonkungen.com\/de\/wp-json\/wp\/v2\/comments?post=11748"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xenonkungen.com\/de\/wp-json\/wp\/v2\/media\/11116"}],"wp:attachment":[{"href":"https:\/\/xenonkungen.com\/de\/wp-json\/wp\/v2\/media?parent=11748"}],"wp:term":[{"taxonomy":"anvandningsomrade","embeddable":true,"href":"https:\/\/xenonkungen.com\/de\/wp-json\/wp\/v2\/anvandningsomrade?post=11748"},{"taxonomy":"bilmarken","embeddable":true,"href":"https:\/\/xenonkungen.com\/de\/wp-json\/wp\/v2\/bilmarken?post=11748"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/xenonkungen.com\/de\/wp-json\/wp\/v2\/product_brand?post=11748"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/xenonkungen.com\/de\/wp-json\/wp\/v2\/product_cat?post=11748"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/xenonkungen.com\/de\/wp-json\/wp\/v2\/product_tag?post=11748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}