{"id":26458,"date":"2026-02-19T15:43:35","date_gmt":"2026-02-19T14:43:35","guid":{"rendered":"https:\/\/xenonkungen.com\/?post_type=product&#038;p=26458"},"modified":"2026-04-24T18:14:33","modified_gmt":"2026-04-24T17:14:33","slug":"wago-221-413-spleisverbinder-mit-hebeln-3-adrig-20-p","status":"publish","type":"product","link":"https:\/\/xenonkungen.com\/de\/produkt\/wago-221-413-spleisverbinder-mit-hebeln-3-adrig-20-p\/","title":{"rendered":"Wago 221-413 Hebelverbinder | 3-adrig, 20-polig"},"content":{"rendered":"<p>Flexible und werkzeuglose Anschlussklemme f\u00fcr alle Leitertypen bis 4 mm\u00b2. Transparentes Geh\u00e4use f\u00fcr einfache Sichtpr\u00fcfung und schnelle Installation in professionellen und industriellen Umgebungen.<\/p>\n<p><strong>Schnelle und werkzeuglose Verbindung mit CAGE CLAMP\u00ae<\/strong><\/p>\n<p>Die WAGO 221 ist eine kompakte und leistungsstarke Anschlussklemme f\u00fcr einfache Elektroinstallationen. Dank der cleveren Hebelfunktion \u00f6ffnen Sie die Klemme, f\u00fchren den Leiter (11 mm Abisolierl\u00e4nge) ein und klappen den Hebel wieder herunter \u2013 fertig. Kein Crimpen oder Vorbereiten von Aderendh\u00fclsen erforderlich.<\/p>\n<p>Die Klemme ist f\u00fcr eine Nennspannung von bis zu 450 V und einen Strom von bis zu 32 A ausgelegt und eignet sich daher auch f\u00fcr Installationen mit hohen Lasten. Die bew\u00e4hrte CAGE CLAMP\u00ae-Technologie gew\u00e4hrleistet eine wartungsfreie und sichere Verbindung f\u00fcr massive, mehrdr\u00e4htige und feindr\u00e4htige Kupferleiter.<\/p>\n<p><strong>F\u00fcr alle Leitertypen 0,2\u20134 mm\u00b2<\/strong><\/p>\n<p>Wago 221 ist kompatibel mit:<\/p>\n<ul>\n<li>Massiver Leiter: 0,2\u20134 mm\u00b2 (24\u201312 AWG)<\/li>\n<li>Litzendraht: 0,2\u20134 mm\u00b2 (24\u201312 AWG)<\/li>\n<li>Feinlitzenleiter: 0,14\u20134 mm\u00b2 (24\u201312 AWG)<\/li>\n<\/ul>\n<p>Das transparente Geh\u00e4use erm\u00f6glicht eine einfache Sichtpr\u00fcfung auf korrekten Anschluss. Die breiten, flachen Hebel sind ergonomisch geformt und lassen sich komplett werkzeuglos bedienen.<\/p>\n<p><strong>Kompaktes Design f\u00fcr professionelle Installationen<\/strong><\/p>\n<p>Mit Abmessungen von 18,8 x 8,4 x 18,6 mm (B x H x T) ist die Serie 221 deutlich kompakter als herk\u00f6mmliche Klemmen. Die Hebel liegen im geschlossenen Zustand flach am Geh\u00e4use an, sodass die Klemme auch in engen Verteilerdosen Platz findet.<\/p>\n<p>Das Produkt ist f\u00fcr Umgebungstemperaturen bis 85 \u00b0C (T85) ausgelegt und f\u00fcr Kupferleiter vorgesehen. Einige Varianten sind f\u00fcr bestimmte Ex-Anwendungen zugelassen (siehe Datenblatt).<\/p>\n<p><strong>Effizientere Installation und reduzierte Montagezeit<\/strong><\/p>\n<p>WAGO 221 findet in verschiedensten Bereichen Anwendung, von Wohngeb\u00e4uden \u00fcber Industrieanlagen bis hin zu Haushaltsger\u00e4ten und Steuerungssystemen. Es spart Installationszeit und bietet eine sichere, stabile und dauerhafte Verbindung \u2013 ideal beispielsweise f\u00fcr:<\/p>\n<ul>\n<li>Abzweigverbinder<\/li>\n<li>Beleuchtungsanlagen<\/li>\n<li>Verteilerk\u00e4sten<\/li>\n<li>Elektroschr\u00e4nke und Ger\u00e4teschr\u00e4nke<\/li>\n<li>Service und Wiederaufbau<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p><strong>Klemmenblock 221-413 3-polig 0,2\u20134 mm\u00b2, WAGO<\/strong><\/p>\n<p><strong>20er-Packung<\/strong><\/p>","protected":false},"featured_media":26428,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_smort_price_nok":"197","_smort_price_dkk":"","_smort_price_eur":"","_smort_sale_price_nok":"","_smort_sale_price_dkk":"","_smort_sale_price_eur":"","smort_restorder":"","shipmondo_restorder":"","_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","smort_custom_pricelist_1":"99.6","smort_custom_pricelist_2":"99.6","smort_custom_pricelist_3":"92.6","smort_custom_pricelist_4":"147.2","smort_custom_pricelist_5":"99.6"},"anvandningsomrade":[],"bilmarken":[],"product_brand":[2883],"product_cat":[390],"product_tag":[],"class_list":{"0":"post-26458","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-wago","7":"product_cat-installation","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":47,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wago 221-413 Splicing connector with levers | 3-conductor 20-P - Xenonkungen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xenonkungen.com\/de\/produkt\/wago-221-413-spleisverbinder-mit-hebeln-3-adrig-20-p\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wago 221-413 Splicing connector with levers | 3-conductor 20-P - Xenonkungen\" \/>\n<meta property=\"og:description\" content=\"Kopplingskl\u00e4mma 221-413 3-polig 0,2\u20134mm\u00b2, WAGO  20-PACK\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xenonkungen.com\/de\/produkt\/wago-221-413-spleisverbinder-mit-hebeln-3-adrig-20-p\/\" \/>\n<meta property=\"og:site_name\" content=\"Xenonkungen\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-24T17:14:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/02\/WAGO-3-x-Kontaktdon-3x221-413-XK259561-Org-PNNG-1024x586.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"586\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/xenonkungen.com\/produkt\/wago-221-413-splicing-connector-with-levers-3-conductor-20-p\/\",\"url\":\"https:\/\/xenonkungen.com\/produkt\/wago-221-413-splicing-connector-with-levers-3-conductor-20-p\/\",\"name\":\"Wago 221-413 Splicing connector with levers | 3-conductor 20-P - Xenonkungen\",\"isPartOf\":{\"@id\":\"https:\/\/xenonkungen.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/xenonkungen.com\/produkt\/wago-221-413-splicing-connector-with-levers-3-conductor-20-p\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/xenonkungen.com\/produkt\/wago-221-413-splicing-connector-with-levers-3-conductor-20-p\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/02\/WAGO-3-x-Kontaktdon-3x221-413-XK259561-Org-PNNG.png\",\"datePublished\":\"2026-02-19T14:43:35+00:00\",\"dateModified\":\"2026-04-24T17:14:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/xenonkungen.com\/produkt\/wago-221-413-splicing-connector-with-levers-3-conductor-20-p\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/xenonkungen.com\/produkt\/wago-221-413-splicing-connector-with-levers-3-conductor-20-p\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/xenonkungen.com\/produkt\/wago-221-413-splicing-connector-with-levers-3-conductor-20-p\/#primaryimage\",\"url\":\"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/02\/WAGO-3-x-Kontaktdon-3x221-413-XK259561-Org-PNNG.png\",\"contentUrl\":\"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/02\/WAGO-3-x-Kontaktdon-3x221-413-XK259561-Org-PNNG.png\",\"width\":2000,\"height\":1145},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/xenonkungen.com\/produkt\/wago-221-413-splicing-connector-with-levers-3-conductor-20-p\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hem\",\"item\":\"https:\/\/xenonkungen.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/xenonkungen.com\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Wago 221-413 Splicing connector with levers | 3-conductor 20-P\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/xenonkungen.com\/#website\",\"url\":\"https:\/\/xenonkungen.com\/\",\"name\":\"Xenonkungen\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/xenonkungen.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wago 221-413 Splei\u00dfverbinder mit Hebeln | 3-adrig 20-P \u2013 Der Xenon-K\u00f6nig","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xenonkungen.com\/de\/produkt\/wago-221-413-spleisverbinder-mit-hebeln-3-adrig-20-p\/","og_locale":"de_DE","og_type":"article","og_title":"Wago 221-413 Splicing connector with levers | 3-conductor 20-P - Xenonkungen","og_description":"Kopplingskl\u00e4mma 221-413 3-polig 0,2\u20134mm\u00b2, WAGO  20-PACK","og_url":"https:\/\/xenonkungen.com\/de\/produkt\/wago-221-413-spleisverbinder-mit-hebeln-3-adrig-20-p\/","og_site_name":"Xenonkungen","article_modified_time":"2026-04-24T17:14:33+00:00","og_image":[{"width":1024,"height":586,"url":"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/02\/WAGO-3-x-Kontaktdon-3x221-413-XK259561-Org-PNNG-1024x586.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/xenonkungen.com\/produkt\/wago-221-413-splicing-connector-with-levers-3-conductor-20-p\/","url":"https:\/\/xenonkungen.com\/produkt\/wago-221-413-splicing-connector-with-levers-3-conductor-20-p\/","name":"Wago 221-413 Splei\u00dfverbinder mit Hebeln | 3-adrig 20-P \u2013 Der Xenon-K\u00f6nig","isPartOf":{"@id":"https:\/\/xenonkungen.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/xenonkungen.com\/produkt\/wago-221-413-splicing-connector-with-levers-3-conductor-20-p\/#primaryimage"},"image":{"@id":"https:\/\/xenonkungen.com\/produkt\/wago-221-413-splicing-connector-with-levers-3-conductor-20-p\/#primaryimage"},"thumbnailUrl":"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/02\/WAGO-3-x-Kontaktdon-3x221-413-XK259561-Org-PNNG.png","datePublished":"2026-02-19T14:43:35+00:00","dateModified":"2026-04-24T17:14:33+00:00","breadcrumb":{"@id":"https:\/\/xenonkungen.com\/produkt\/wago-221-413-splicing-connector-with-levers-3-conductor-20-p\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xenonkungen.com\/produkt\/wago-221-413-splicing-connector-with-levers-3-conductor-20-p\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/xenonkungen.com\/produkt\/wago-221-413-splicing-connector-with-levers-3-conductor-20-p\/#primaryimage","url":"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/02\/WAGO-3-x-Kontaktdon-3x221-413-XK259561-Org-PNNG.png","contentUrl":"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/02\/WAGO-3-x-Kontaktdon-3x221-413-XK259561-Org-PNNG.png","width":2000,"height":1145},{"@type":"BreadcrumbList","@id":"https:\/\/xenonkungen.com\/produkt\/wago-221-413-splicing-connector-with-levers-3-conductor-20-p\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hem","item":"https:\/\/xenonkungen.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/xenonkungen.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Wago 221-413 Splicing connector with levers | 3-conductor 20-P"}]},{"@type":"WebSite","@id":"https:\/\/xenonkungen.com\/#website","url":"https:\/\/xenonkungen.com\/","name":"Xenonkungen","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xenonkungen.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"taxonomy_info":{"product_brand":[{"value":2883,"label":"Wago"}],"product_cat":[{"value":390,"label":"Installation"}]},"featured_image_src_large":["https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/02\/WAGO-3-x-Kontaktdon-3x221-413-XK259561-Org-PNNG-1024x586.png",1024,586,true],"author_info":[],"comment_info":0,"_links":{"self":[{"href":"https:\/\/xenonkungen.com\/de\/wp-json\/wp\/v2\/product\/26458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xenonkungen.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/xenonkungen.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/xenonkungen.com\/de\/wp-json\/wp\/v2\/comments?post=26458"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xenonkungen.com\/de\/wp-json\/wp\/v2\/media\/26428"}],"wp:attachment":[{"href":"https:\/\/xenonkungen.com\/de\/wp-json\/wp\/v2\/media?parent=26458"}],"wp:term":[{"taxonomy":"anvandningsomrade","embeddable":true,"href":"https:\/\/xenonkungen.com\/de\/wp-json\/wp\/v2\/anvandningsomrade?post=26458"},{"taxonomy":"bilmarken","embeddable":true,"href":"https:\/\/xenonkungen.com\/de\/wp-json\/wp\/v2\/bilmarken?post=26458"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/xenonkungen.com\/de\/wp-json\/wp\/v2\/product_brand?post=26458"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/xenonkungen.com\/de\/wp-json\/wp\/v2\/product_cat?post=26458"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/xenonkungen.com\/de\/wp-json\/wp\/v2\/product_tag?post=26458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}