{"id":27947,"date":"2026-03-16T14:12:45","date_gmt":"2026-03-16T13:12:45","guid":{"rendered":"https:\/\/xenonkungen.com\/?post_type=product&#038;p=27947"},"modified":"2026-05-12T14:51:22","modified_gmt":"2026-05-12T13:51:22","slug":"tershine-rekondpenslar","status":"publish","type":"product","link":"https:\/\/xenonkungen.com\/de\/produkt\/tershine-rekondpenslar\/","title":{"rendered":"Tershine Recond Pinsel"},"content":{"rendered":"<p>Dreierpackung hochwertiger, wiederaufbereiteter B\u00fcrsten. Perfekt in Kombination mit unserem Allzweckreiniger APC.<\/p>\n<p><strong>Unverzichtbar f\u00fcr die gr\u00fcndliche Reinigung des Innenraums<br \/>\nDrei verschiedene Gr\u00f6\u00dfen<br \/>\nChemikalienbest\u00e4ndig<br \/>\nHohe Qualit\u00e4t<br \/>\nViele Anwendungsbereiche<\/strong><\/p>\n<p>Hochwertige B\u00fcrsten in drei verschiedenen Gr\u00f6\u00dfen. Ideal f\u00fcr alle schwer zug\u00e4nglichen Stellen wie Felgen, Innenraum, Verkleidungen, L\u00fcftergitter, Motorraum usw. Sanfte, mittelweiche Borsten und ein robuster Kunststoffgriff.<\/p>\n<p>Eine tolle Kombination mit APC \u2013 Allzweckreiniger oder warum nicht Relive \u2013 Rostentferner f\u00fcr Felgen?<\/p>\n<p>Verkauft im Dreier-Set und geliefert in einem ordentlichen Karton!<\/p>\n<p><strong>Gr\u00f6\u00dfen:<\/strong>\u00a012 mm, 16 mm und 20 mm.<\/p>","protected":false},"excerpt":{"rendered":"<p>3-pack rekondpenslar av mycket h\u00f6g kvalitet.<\/p>","protected":false},"featured_media":27948,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_smort_price_nok":"","_smort_price_dkk":"","_smort_price_eur":"","_smort_sale_price_nok":"","_smort_sale_price_dkk":"","_smort_sale_price_eur":"","smort_restorder":"","shipmondo_restorder":"","_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","smort_custom_pricelist_1":"95.36","smort_custom_pricelist_2":"95.36","smort_custom_pricelist_3":"95.36","smort_custom_pricelist_4":"119.2","smort_custom_pricelist_5":"95.36"},"anvandningsomrade":[],"bilmarken":[],"product_brand":[2893],"product_cat":[2988,2450,2892,378],"product_tag":[],"class_list":{"0":"post-27947","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-tershine","7":"product_cat-biltvatt","8":"product_cat-tillbehor-bilvard","9":"product_cat-retail-produkter","10":"product_cat-bilvard","12":"first","13":"onbackorder","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"bundled_by":[],"bundle_stock_status":"onbackorder","bundle_stock_quantity":0,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tershine Rekondpenslar - Xenonkungen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xenonkungen.com\/de\/produkt\/tershine-rekondpenslar\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tershine Rekondpenslar - Xenonkungen\" \/>\n<meta property=\"og:description\" content=\"3-pack rekondpenslar av mycket h\u00f6g kvalitet.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xenonkungen.com\/de\/produkt\/tershine-rekondpenslar\/\" \/>\n<meta property=\"og:site_name\" content=\"Xenonkungen\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T13:51:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/03\/73Ty9KN4OmvQCr08B5KFOSzBfki7dKF8FbuFnMbP.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/xenonkungen.com\/produkt\/tershine-rekondpenslar\/\",\"url\":\"https:\/\/xenonkungen.com\/produkt\/tershine-rekondpenslar\/\",\"name\":\"Tershine Rekondpenslar - Xenonkungen\",\"isPartOf\":{\"@id\":\"https:\/\/xenonkungen.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/xenonkungen.com\/produkt\/tershine-rekondpenslar\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/xenonkungen.com\/produkt\/tershine-rekondpenslar\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/03\/73Ty9KN4OmvQCr08B5KFOSzBfki7dKF8FbuFnMbP.webp\",\"datePublished\":\"2026-03-16T13:12:45+00:00\",\"dateModified\":\"2026-05-12T13:51:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/xenonkungen.com\/produkt\/tershine-rekondpenslar\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/xenonkungen.com\/produkt\/tershine-rekondpenslar\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/xenonkungen.com\/produkt\/tershine-rekondpenslar\/#primaryimage\",\"url\":\"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/03\/73Ty9KN4OmvQCr08B5KFOSzBfki7dKF8FbuFnMbP.webp\",\"contentUrl\":\"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/03\/73Ty9KN4OmvQCr08B5KFOSzBfki7dKF8FbuFnMbP.webp\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/xenonkungen.com\/produkt\/tershine-rekondpenslar\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hem\",\"item\":\"https:\/\/xenonkungen.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/xenonkungen.com\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tershine Rekondpenslar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/xenonkungen.com\/#website\",\"url\":\"https:\/\/xenonkungen.com\/\",\"name\":\"Xenonkungen\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/xenonkungen.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tershine Rekondpenslar - Xenonkungen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xenonkungen.com\/de\/produkt\/tershine-rekondpenslar\/","og_locale":"de_DE","og_type":"article","og_title":"Tershine Rekondpenslar - Xenonkungen","og_description":"3-pack rekondpenslar av mycket h\u00f6g kvalitet.","og_url":"https:\/\/xenonkungen.com\/de\/produkt\/tershine-rekondpenslar\/","og_site_name":"Xenonkungen","article_modified_time":"2026-05-12T13:51:22+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/03\/73Ty9KN4OmvQCr08B5KFOSzBfki7dKF8FbuFnMbP.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/xenonkungen.com\/produkt\/tershine-rekondpenslar\/","url":"https:\/\/xenonkungen.com\/produkt\/tershine-rekondpenslar\/","name":"Tershine Rekondpenslar - Xenonkungen","isPartOf":{"@id":"https:\/\/xenonkungen.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/xenonkungen.com\/produkt\/tershine-rekondpenslar\/#primaryimage"},"image":{"@id":"https:\/\/xenonkungen.com\/produkt\/tershine-rekondpenslar\/#primaryimage"},"thumbnailUrl":"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/03\/73Ty9KN4OmvQCr08B5KFOSzBfki7dKF8FbuFnMbP.webp","datePublished":"2026-03-16T13:12:45+00:00","dateModified":"2026-05-12T13:51:22+00:00","breadcrumb":{"@id":"https:\/\/xenonkungen.com\/produkt\/tershine-rekondpenslar\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xenonkungen.com\/produkt\/tershine-rekondpenslar\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/xenonkungen.com\/produkt\/tershine-rekondpenslar\/#primaryimage","url":"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/03\/73Ty9KN4OmvQCr08B5KFOSzBfki7dKF8FbuFnMbP.webp","contentUrl":"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/03\/73Ty9KN4OmvQCr08B5KFOSzBfki7dKF8FbuFnMbP.webp","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/xenonkungen.com\/produkt\/tershine-rekondpenslar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hem","item":"https:\/\/xenonkungen.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/xenonkungen.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Tershine Rekondpenslar"}]},{"@type":"WebSite","@id":"https:\/\/xenonkungen.com\/#website","url":"https:\/\/xenonkungen.com\/","name":"Xenonkungen","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xenonkungen.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"taxonomy_info":{"product_brand":[{"value":2893,"label":"Tershine"}],"product_cat":[{"value":2988,"label":"1 | Biltv\u00e4tt"},{"value":2450,"label":"6 | Tillbeh\u00f6r"},{"value":2892,"label":"\u00c5terf\u00f6rs\u00e4ljarprodukter"},{"value":378,"label":"Bilv\u00e5rd"}]},"featured_image_src_large":["https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/03\/73Ty9KN4OmvQCr08B5KFOSzBfki7dKF8FbuFnMbP.webp",1024,1024,false],"author_info":[],"comment_info":0,"_links":{"self":[{"href":"https:\/\/xenonkungen.com\/de\/wp-json\/wp\/v2\/product\/27947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xenonkungen.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/xenonkungen.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/xenonkungen.com\/de\/wp-json\/wp\/v2\/comments?post=27947"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xenonkungen.com\/de\/wp-json\/wp\/v2\/media\/27948"}],"wp:attachment":[{"href":"https:\/\/xenonkungen.com\/de\/wp-json\/wp\/v2\/media?parent=27947"}],"wp:term":[{"taxonomy":"anvandningsomrade","embeddable":true,"href":"https:\/\/xenonkungen.com\/de\/wp-json\/wp\/v2\/anvandningsomrade?post=27947"},{"taxonomy":"bilmarken","embeddable":true,"href":"https:\/\/xenonkungen.com\/de\/wp-json\/wp\/v2\/bilmarken?post=27947"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/xenonkungen.com\/de\/wp-json\/wp\/v2\/product_brand?post=27947"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/xenonkungen.com\/de\/wp-json\/wp\/v2\/product_cat?post=27947"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/xenonkungen.com\/de\/wp-json\/wp\/v2\/product_tag?post=27947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}