{"id":28161,"date":"2026-03-18T10:29:38","date_gmt":"2026-03-18T09:29:38","guid":{"rendered":"https:\/\/xenonkungen.com\/?post_type=product&#038;p=28161"},"modified":"2026-05-12T14:41:00","modified_gmt":"2026-05-12T13:41:00","slug":"tershine-polierscheibe-starker-abtrag","status":"publish","type":"product","link":"https:\/\/xenonkungen.com\/de\/produkt\/tershine-polierscheibe-starker-abtrag\/","title":{"rendered":"Tershine Polierscheibe \u2013 Grober Schnitt"},"content":{"rendered":"<p>Das\u00a0<strong data-start=\"252\" data-end=\"293\">Polierscheibe mit Hartschaum (starker Abtrag)<\/strong>\u00a0wurde entwickelt, um die\u00a0<strong data-start=\"329\" data-end=\"355\">schwierigste Lackprobleme<\/strong>\u00a0\u2013 wie beispielsweise tiefe Kratzer, starke Oxidation und andere gravierende M\u00e4ngel. Dank seiner\u00a0<strong data-start=\"433\" data-end=\"465\">hohe Qualit\u00e4t und Langlebigkeit<\/strong>\u00a0Es erm\u00f6glicht effizientes Schneiden und bew\u00e4ltigt auch anspruchsvolle Polierarbeiten ohne Kompromisse.<\/p>\n<p data-start=\"544\" data-end=\"762\">Perfekt geeignet f\u00fcr die Verwendung auf<span class=\"Apple-converted-space\">\u00a0<\/span><strong data-start=\"577\" data-end=\"637\">alle Arten von Lacken, Gelcoat, Plexiglas und \u00e4hnlichen Oberfl\u00e4chen<\/strong>Dank des universellen Designs ist es f\u00fcr beides geeignet.<span class=\"Apple-converted-space\">\u00a0<\/span><strong data-start=\"686\" data-end=\"730\">Rotations- und Oszillationspoliermaschinen<\/strong><span class=\"Apple-converted-space\">\u00a0<\/span>mit 125 mm (5\u2033) Scheibenhalter.<\/p>\n<ul data-start=\"764\" data-end=\"1053\">\n<li data-start=\"764\" data-end=\"812\">\n<p data-start=\"766\" data-end=\"812\">Hartschaum (stark geschnitten) f\u00fcr maximale Schneidleistung<\/p>\n<\/li>\n<li data-start=\"813\" data-end=\"875\">\n<p data-start=\"815\" data-end=\"875\">Entfernt tiefe Kratzer, starke Oxidation und grobe Defekte<\/p>\n<\/li>\n<li data-start=\"876\" data-end=\"926\">\n<p data-start=\"878\" data-end=\"926\">F\u00fcr Lacke, Gelcoat, Plexiglas und weitere Materialien<\/p>\n<\/li>\n<li data-start=\"927\" data-end=\"981\">\n<p data-start=\"929\" data-end=\"981\">Kompatibel mit rotierenden und oszillierenden Maschinen<\/p>\n<\/li>\n<li data-start=\"982\" data-end=\"1007\">\n<p data-start=\"984\" data-end=\"1007\">Durchmesser: 125 mm (5\u2033)<\/p>\n<\/li>\n<li data-start=\"1008\" data-end=\"1053\">\n<p data-start=\"1010\" data-end=\"1053\">Waschbar und f\u00fcr den Langzeitgebrauch konzipiert.<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"1055\" data-end=\"1110\"><strong data-start=\"1055\" data-end=\"1110\">Eine leistungsstarke Riemenscheibe f\u00fcr anspruchsvolle Herausforderungen in der Autopflege.<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Hochwertige, grobk\u00f6rnige Schaumstoffpolierscheibe zum Polieren aller Arten von Lacken, Gelcoat, Plexiglas usw.<\/p>","protected":false},"featured_media":28164,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_smort_price_nok":"","_smort_price_dkk":"","_smort_price_eur":"","_smort_sale_price_nok":"","_smort_sale_price_dkk":"","_smort_sale_price_eur":"","smort_restorder":"","shipmondo_restorder":"","_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","smort_custom_pricelist_1":"63.36","smort_custom_pricelist_2":"63.36","smort_custom_pricelist_3":"63.36","smort_custom_pricelist_4":"79.2","smort_custom_pricelist_5":"63.36"},"anvandningsomrade":[],"bilmarken":[],"product_brand":[2893],"product_cat":[2989,2617,2615,378],"product_tag":[],"class_list":{"0":"post-28161","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-tershine","7":"product_cat-avfettning","8":"product_cat-polering","9":"product_cat-polertrissor","10":"product_cat-bilvard","12":"first","13":"onbackorder","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"bundled_by":[],"bundle_stock_status":"onbackorder","bundle_stock_quantity":0,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tershine Polertrissa - Heavy cut - Xenonkungen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xenonkungen.com\/de\/produkt\/tershine-polierscheibe-starker-abtrag\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tershine Polertrissa - Heavy cut - Xenonkungen\" \/>\n<meta property=\"og:description\" content=\"Skumpolerstrissa heavy cut av mycket h\u00f6g kvalitet f\u00f6r att polera alla typer av lack, gealcoat, plexiglas osv.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xenonkungen.com\/de\/produkt\/tershine-polierscheibe-starker-abtrag\/\" \/>\n<meta property=\"og:site_name\" content=\"Xenonkungen\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T13:41:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/03\/qf9Q67lV83XepQoq3xBYvnGgf7WJLVyFcfSKkZ5H.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/xenonkungen.com\/produkt\/tershine-polertrissa-heavy-cut\/\",\"url\":\"https:\/\/xenonkungen.com\/produkt\/tershine-polertrissa-heavy-cut\/\",\"name\":\"Tershine Polertrissa - Heavy cut - Xenonkungen\",\"isPartOf\":{\"@id\":\"https:\/\/xenonkungen.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/xenonkungen.com\/produkt\/tershine-polertrissa-heavy-cut\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/xenonkungen.com\/produkt\/tershine-polertrissa-heavy-cut\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/03\/qf9Q67lV83XepQoq3xBYvnGgf7WJLVyFcfSKkZ5H.webp\",\"datePublished\":\"2026-03-18T09:29:38+00:00\",\"dateModified\":\"2026-05-12T13:41:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/xenonkungen.com\/produkt\/tershine-polertrissa-heavy-cut\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/xenonkungen.com\/produkt\/tershine-polertrissa-heavy-cut\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/xenonkungen.com\/produkt\/tershine-polertrissa-heavy-cut\/#primaryimage\",\"url\":\"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/03\/qf9Q67lV83XepQoq3xBYvnGgf7WJLVyFcfSKkZ5H.webp\",\"contentUrl\":\"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/03\/qf9Q67lV83XepQoq3xBYvnGgf7WJLVyFcfSKkZ5H.webp\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/xenonkungen.com\/produkt\/tershine-polertrissa-heavy-cut\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hem\",\"item\":\"https:\/\/xenonkungen.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/xenonkungen.com\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tershine Polertrissa &#8211; Heavy cut\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/xenonkungen.com\/#website\",\"url\":\"https:\/\/xenonkungen.com\/\",\"name\":\"Xenonkungen\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/xenonkungen.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tershine Polierscheibe - Grober Schnitt - Xenonkungen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xenonkungen.com\/de\/produkt\/tershine-polierscheibe-starker-abtrag\/","og_locale":"de_DE","og_type":"article","og_title":"Tershine Polertrissa - Heavy cut - Xenonkungen","og_description":"Skumpolerstrissa heavy cut av mycket h\u00f6g kvalitet f\u00f6r att polera alla typer av lack, gealcoat, plexiglas osv.","og_url":"https:\/\/xenonkungen.com\/de\/produkt\/tershine-polierscheibe-starker-abtrag\/","og_site_name":"Xenonkungen","article_modified_time":"2026-05-12T13:41:00+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/03\/qf9Q67lV83XepQoq3xBYvnGgf7WJLVyFcfSKkZ5H.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/xenonkungen.com\/produkt\/tershine-polertrissa-heavy-cut\/","url":"https:\/\/xenonkungen.com\/produkt\/tershine-polertrissa-heavy-cut\/","name":"Tershine Polierscheibe - Grober Schnitt - Xenonkungen","isPartOf":{"@id":"https:\/\/xenonkungen.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/xenonkungen.com\/produkt\/tershine-polertrissa-heavy-cut\/#primaryimage"},"image":{"@id":"https:\/\/xenonkungen.com\/produkt\/tershine-polertrissa-heavy-cut\/#primaryimage"},"thumbnailUrl":"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/03\/qf9Q67lV83XepQoq3xBYvnGgf7WJLVyFcfSKkZ5H.webp","datePublished":"2026-03-18T09:29:38+00:00","dateModified":"2026-05-12T13:41:00+00:00","breadcrumb":{"@id":"https:\/\/xenonkungen.com\/produkt\/tershine-polertrissa-heavy-cut\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xenonkungen.com\/produkt\/tershine-polertrissa-heavy-cut\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/xenonkungen.com\/produkt\/tershine-polertrissa-heavy-cut\/#primaryimage","url":"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/03\/qf9Q67lV83XepQoq3xBYvnGgf7WJLVyFcfSKkZ5H.webp","contentUrl":"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/03\/qf9Q67lV83XepQoq3xBYvnGgf7WJLVyFcfSKkZ5H.webp","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/xenonkungen.com\/produkt\/tershine-polertrissa-heavy-cut\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hem","item":"https:\/\/xenonkungen.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/xenonkungen.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Tershine Polertrissa &#8211; Heavy cut"}]},{"@type":"WebSite","@id":"https:\/\/xenonkungen.com\/#website","url":"https:\/\/xenonkungen.com\/","name":"Xenonkungen","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xenonkungen.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"taxonomy_info":{"product_brand":[{"value":2893,"label":"Tershine"}],"product_cat":[{"value":2989,"label":"2 | Avfettning"},{"value":2617,"label":"3 | Polering"},{"value":2615,"label":"Polertrissor"},{"value":378,"label":"Bilv\u00e5rd"}]},"featured_image_src_large":["https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/03\/qf9Q67lV83XepQoq3xBYvnGgf7WJLVyFcfSKkZ5H.webp",1024,1024,false],"author_info":[],"comment_info":0,"_links":{"self":[{"href":"https:\/\/xenonkungen.com\/de\/wp-json\/wp\/v2\/product\/28161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xenonkungen.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/xenonkungen.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/xenonkungen.com\/de\/wp-json\/wp\/v2\/comments?post=28161"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xenonkungen.com\/de\/wp-json\/wp\/v2\/media\/28164"}],"wp:attachment":[{"href":"https:\/\/xenonkungen.com\/de\/wp-json\/wp\/v2\/media?parent=28161"}],"wp:term":[{"taxonomy":"anvandningsomrade","embeddable":true,"href":"https:\/\/xenonkungen.com\/de\/wp-json\/wp\/v2\/anvandningsomrade?post=28161"},{"taxonomy":"bilmarken","embeddable":true,"href":"https:\/\/xenonkungen.com\/de\/wp-json\/wp\/v2\/bilmarken?post=28161"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/xenonkungen.com\/de\/wp-json\/wp\/v2\/product_brand?post=28161"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/xenonkungen.com\/de\/wp-json\/wp\/v2\/product_cat?post=28161"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/xenonkungen.com\/de\/wp-json\/wp\/v2\/product_tag?post=28161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}