{"id":31296,"date":"2026-05-19T14:10:50","date_gmt":"2026-05-19T13:10:50","guid":{"rendered":"https:\/\/xenonkungen.com\/produkt\/led-list-5-meter-12w-m-rod-gron-bla-ip20-24v-8mm\/"},"modified":"2026-08-27T13:34:36","modified_gmt":"2026-08-27T12:34:36","slug":"tira-de-led-de-5-metros-12-w-rojo-verde-azul-ip20-24-v-8-mm","status":"publish","type":"product","link":"https:\/\/xenonkungen.com\/es\/producto\/tira-de-led-de-5-metros-12-w-rojo-verde-azul-ip20-24-v-8-mm\/","title":{"rendered":"Tira de LED (5 metros) 12W\/m Rojo\/Verde\/Azul IP20 24V, 8mm"},"content":{"rendered":"<h2>Tira de LED (5 metros) 12W\/m Rojo\/Verde\/Azul IP20 24V, 8mm<\/h2>\n<p>Tira de LED (5 metros) 12W\/M Rojo\/Verde\/Azul IP20 24V, 8mm Esta tira de LED es perfecta para crear un ambiente colorido y agradable en su hogar u oficina. Con una longitud de 5 metros y una potencia de 12W por metro, proporciona suficiente luz para<\/p>\n<h2>Especificaciones<\/h2>\n<ul>\n<li><strong>Color<\/strong> - Rojo<\/li>\n<li><strong>Voltaje<\/strong> \u2013 24V<\/li>\n<li><strong>Efecto<\/strong> \u2013 12W<\/li>\n<\/ul>\n<h2>Compra en Xenonkungen<\/h2>\n<p>Entrega r\u00e1pida y plazo de compra de 30 d\u00edas.<\/p>","protected":false},"excerpt":{"rendered":"<p>Tira de LED (5 metros) 12W\/M Rojo\/Verde\/Azul IP20 24V, 8mm de Star Trading, rojo.<\/p>","protected":false},"featured_media":31294,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_smort_price_nok":"","_smort_price_dkk":"","_smort_price_eur":"34.45","_smort_sale_price_nok":"","_smort_sale_price_dkk":"","_smort_sale_price_eur":"","smort_restorder":"","shipmondo_restorder":"","_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","smort_custom_pricelist_1":"242.56","smort_custom_pricelist_2":"212.24","smort_custom_pricelist_3":"197.08","smort_custom_pricelist_4":"303.2","smort_custom_pricelist_5":"212.24"},"anvandningsomrade":[3288],"bilmarken":[],"product_brand":[],"product_cat":[3082],"product_tag":[],"class_list":["post-31296","product","type-product","status-publish","has-post-thumbnail","anvandningsomrade-hem","product_cat-led-lister-hem","pa_farg-rod","pa_fuktskydd-varde-ipxx-ip20","pa_volt-v-24v","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":13,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LED-List (5 meter) 12W\/M R\u00f6d\/Gr\u00f6n\/Bl\u00e5 IP | Xenonkungen<\/title>\n<meta name=\"description\" content=\"LED-List (5 meter) 12W\/M R\u00f6d\/Gr\u00f6n\/Bl\u00e5 IP20 24V, 8mm \u2013 Snabb leverans, \u00f6ppet k\u00f6p 30 dagar.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xenonkungen.com\/es\/producto\/tira-de-led-de-5-metros-12-w-rojo-verde-azul-ip20-24-v-8-mm\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LED-List (5 meter) 12W\/M R\u00f6d\/Gr\u00f6n\/Bl\u00e5 IP | Xenonkungen\" \/>\n<meta property=\"og:description\" content=\"LED-List (5 meter) 12W\/M R\u00f6d\/Gr\u00f6n\/Bl\u00e5 IP20 24V, 8mm \u2013 Snabb leverans, \u00f6ppet k\u00f6p 30 dagar.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xenonkungen.com\/es\/producto\/tira-de-led-de-5-metros-12-w-rojo-verde-azul-ip20-24-v-8-mm\/\" \/>\n<meta property=\"og:site_name\" content=\"Xenonkungen\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-27T12:34:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/05\/lk-1721_MN.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/xenonkungen.com\/produkt\/led-list-5-meter-12w-m-rod-gron-bla-ip20-24v-8mm\/\",\"url\":\"https:\/\/xenonkungen.com\/produkt\/led-list-5-meter-12w-m-rod-gron-bla-ip20-24v-8mm\/\",\"name\":\"LED-List (5 meter) 12W\/M R\u00f6d\/Gr\u00f6n\/Bl\u00e5 IP | Xenonkungen\",\"isPartOf\":{\"@id\":\"https:\/\/xenonkungen.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/xenonkungen.com\/produkt\/led-list-5-meter-12w-m-rod-gron-bla-ip20-24v-8mm\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/xenonkungen.com\/produkt\/led-list-5-meter-12w-m-rod-gron-bla-ip20-24v-8mm\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/05\/lk-1721_MN.png\",\"datePublished\":\"2026-05-19T13:10:50+00:00\",\"dateModified\":\"2026-08-27T12:34:36+00:00\",\"description\":\"LED-List (5 meter) 12W\/M R\u00f6d\/Gr\u00f6n\/Bl\u00e5 IP20 24V, 8mm \u2013 Snabb leverans, \u00f6ppet k\u00f6p 30 dagar.\",\"breadcrumb\":{\"@id\":\"https:\/\/xenonkungen.com\/produkt\/led-list-5-meter-12w-m-rod-gron-bla-ip20-24v-8mm\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/xenonkungen.com\/produkt\/led-list-5-meter-12w-m-rod-gron-bla-ip20-24v-8mm\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/xenonkungen.com\/produkt\/led-list-5-meter-12w-m-rod-gron-bla-ip20-24v-8mm\/#primaryimage\",\"url\":\"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/05\/lk-1721_MN.png\",\"contentUrl\":\"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/05\/lk-1721_MN.png\",\"width\":800,\"height\":800,\"caption\":\"IMPORT_LEDKUNGEN\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/xenonkungen.com\/produkt\/led-list-5-meter-12w-m-rod-gron-bla-ip20-24v-8mm\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hem\",\"item\":\"https:\/\/xenonkungen.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/xenonkungen.com\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"LED-List (5 meter) 12W\/M R\u00f6d\/Gr\u00f6n\/Bl\u00e5 IP20 24V, 8mm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/xenonkungen.com\/#website\",\"url\":\"https:\/\/xenonkungen.com\/\",\"name\":\"Xenonkungen\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/xenonkungen.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tira de LED (5 metros) 12W\/m Rojo\/Verde\/Azul IP | Xenonkungen","description":"Tira de LED (5 metros) 12W\/M Rojo\/Verde\/Azul IP20 24V, 8mm \u2013 Entrega r\u00e1pida, plazo de compra de 30 d\u00edas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xenonkungen.com\/es\/producto\/tira-de-led-de-5-metros-12-w-rojo-verde-azul-ip20-24-v-8-mm\/","og_locale":"es_ES","og_type":"article","og_title":"LED-List (5 meter) 12W\/M R\u00f6d\/Gr\u00f6n\/Bl\u00e5 IP | Xenonkungen","og_description":"LED-List (5 meter) 12W\/M R\u00f6d\/Gr\u00f6n\/Bl\u00e5 IP20 24V, 8mm \u2013 Snabb leverans, \u00f6ppet k\u00f6p 30 dagar.","og_url":"https:\/\/xenonkungen.com\/es\/producto\/tira-de-led-de-5-metros-12-w-rojo-verde-azul-ip20-24-v-8-mm\/","og_site_name":"Xenonkungen","article_modified_time":"2026-08-27T12:34:36+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/05\/lk-1721_MN.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/xenonkungen.com\/produkt\/led-list-5-meter-12w-m-rod-gron-bla-ip20-24v-8mm\/","url":"https:\/\/xenonkungen.com\/produkt\/led-list-5-meter-12w-m-rod-gron-bla-ip20-24v-8mm\/","name":"Tira de LED (5 metros) 12W\/m Rojo\/Verde\/Azul IP | Xenonkungen","isPartOf":{"@id":"https:\/\/xenonkungen.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/xenonkungen.com\/produkt\/led-list-5-meter-12w-m-rod-gron-bla-ip20-24v-8mm\/#primaryimage"},"image":{"@id":"https:\/\/xenonkungen.com\/produkt\/led-list-5-meter-12w-m-rod-gron-bla-ip20-24v-8mm\/#primaryimage"},"thumbnailUrl":"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/05\/lk-1721_MN.png","datePublished":"2026-05-19T13:10:50+00:00","dateModified":"2026-08-27T12:34:36+00:00","description":"Tira de LED (5 metros) 12W\/M Rojo\/Verde\/Azul IP20 24V, 8mm \u2013 Entrega r\u00e1pida, plazo de compra de 30 d\u00edas.","breadcrumb":{"@id":"https:\/\/xenonkungen.com\/produkt\/led-list-5-meter-12w-m-rod-gron-bla-ip20-24v-8mm\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xenonkungen.com\/produkt\/led-list-5-meter-12w-m-rod-gron-bla-ip20-24v-8mm\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/xenonkungen.com\/produkt\/led-list-5-meter-12w-m-rod-gron-bla-ip20-24v-8mm\/#primaryimage","url":"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/05\/lk-1721_MN.png","contentUrl":"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/05\/lk-1721_MN.png","width":800,"height":800,"caption":"IMPORT_LEDKUNGEN"},{"@type":"BreadcrumbList","@id":"https:\/\/xenonkungen.com\/produkt\/led-list-5-meter-12w-m-rod-gron-bla-ip20-24v-8mm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hem","item":"https:\/\/xenonkungen.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/xenonkungen.com\/shop\/"},{"@type":"ListItem","position":3,"name":"LED-List (5 meter) 12W\/M R\u00f6d\/Gr\u00f6n\/Bl\u00e5 IP20 24V, 8mm"}]},{"@type":"WebSite","@id":"https:\/\/xenonkungen.com\/#website","url":"https:\/\/xenonkungen.com\/","name":"Xenonkungen","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xenonkungen.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"taxonomy_info":{"anvandningsomrade":[{"value":3288,"label":"Hem"}],"product_cat":[{"value":3082,"label":"LED-lister"}],"pa_farg":[{"value":2254,"label":"R\u00f6d"}],"pa_fuktskydd-varde-ipxx":[{"value":1993,"label":"IP20"}],"pa_volt-v":[{"value":853,"label":"24V"}]},"featured_image_src_large":["https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/05\/lk-1721_MN.png",800,800,false],"author_info":[],"comment_info":0,"_links":{"self":[{"href":"https:\/\/xenonkungen.com\/es\/wp-json\/wp\/v2\/product\/31296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xenonkungen.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/xenonkungen.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/xenonkungen.com\/es\/wp-json\/wp\/v2\/comments?post=31296"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xenonkungen.com\/es\/wp-json\/wp\/v2\/media\/31294"}],"wp:attachment":[{"href":"https:\/\/xenonkungen.com\/es\/wp-json\/wp\/v2\/media?parent=31296"}],"wp:term":[{"taxonomy":"anvandningsomrade","embeddable":true,"href":"https:\/\/xenonkungen.com\/es\/wp-json\/wp\/v2\/anvandningsomrade?post=31296"},{"taxonomy":"bilmarken","embeddable":true,"href":"https:\/\/xenonkungen.com\/es\/wp-json\/wp\/v2\/bilmarken?post=31296"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/xenonkungen.com\/es\/wp-json\/wp\/v2\/product_brand?post=31296"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/xenonkungen.com\/es\/wp-json\/wp\/v2\/product_cat?post=31296"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/xenonkungen.com\/es\/wp-json\/wp\/v2\/product_tag?post=31296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}