{"id":31971,"date":"2026-05-19T20:19:54","date_gmt":"2026-05-19T19:19:54","guid":{"rendered":"https:\/\/xenonkungen.com\/produkt\/led-lampa-e27-g125-decoled-spiral-clear-3-step-memory-4-0w-2100k-3-step-dim-memory\/"},"modified":"2026-07-07T14:43:01","modified_gmt":"2026-07-07T13:43:01","slug":"lampara-led-e27-g125-espiral-transparente-memoria-de-3-niveles-40-w-2100-k-memoria-de-atenuacion-de-3-niveles","status":"publish","type":"product","link":"https:\/\/xenonkungen.com\/es\/producto\/lampara-led-e27-g125-espiral-transparente-memoria-de-3-niveles-40-w-2100-k-memoria-de-atenuacion-de-3-niveles\/","title":{"rendered":"L\u00e1mpara LED E27 G125 Decoled Spiral Clear con memoria de 3 niveles \u2013 4,0 W \u2013 2100 K \u2013 Atenuaci\u00f3n de 3 niveles (memoria) \u2013 Star Trading"},"content":{"rendered":"<h2>L\u00e1mpara LED E27 G125 Decoled Spiral Clear con memoria de 3 niveles \u2013 4,0 W \u2013 2100 K \u2013 Atenuaci\u00f3n en 3 niveles (memoria)<\/h2>\n<p>L\u00e1mpara con regulador de intensidad de 3 niveles y funci\u00f3n de memoria. El brillo se ajusta f\u00e1cilmente encendiendo y apagando el interruptor. Elija entre 68 lm, 135 lm o 270 lm. La temperatura de color es de 2100 K y el casquillo es E27. La l\u00e1mpara se enciende autom\u00e1ticamente con el \u00faltimo nivel de brillo utilizado.<\/p>\n<h2>Especificaciones<\/h2>\n<ul>\n<li><strong>Temperatura de color<\/strong> \u2013 2100K<\/li>\n<li><strong>Base de l\u00e1mpara<\/strong> \u2013 E27<\/li>\n<\/ul>\n<h2>Compra en Xenonkungen<\/h2>\n<p>Entrega r\u00e1pida y plazo de compra de 30 d\u00edas.<\/p>","protected":false},"excerpt":{"rendered":"<p>L\u00e1mpara LED E27 G125 Decoled Spiral Clear con memoria de 3 niveles \u2013 4,0 W \u2013 2100 K \u2013 Atenuaci\u00f3n en 3 niveles (con memoria) de Star Trading.<\/p>","protected":false},"featured_media":31969,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_smort_price_nok":"","_smort_price_dkk":"","_smort_price_eur":"14.45","_smort_sale_price_nok":"","_smort_sale_price_dkk":"","_smort_sale_price_eur":"","smort_restorder":"","shipmondo_restorder":"","_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","smort_custom_pricelist_1":"101.76","smort_custom_pricelist_2":"101.76","smort_custom_pricelist_3":"101.76","smort_custom_pricelist_4":"127.2","smort_custom_pricelist_5":"101.76"},"anvandningsomrade":[3288],"bilmarken":[],"product_brand":[],"product_cat":[3104,3093],"product_tag":[],"class_list":["post-31971","product","type-product","status-publish","has-post-thumbnail","anvandningsomrade-hem","product_cat-dekorativa-e-lampor","product_cat-e27-lampor","pa_fuktskydd-varde-ipxx-ip20","pa_lampsockel-kontakt-e27","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":7,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LED-lampa E27 G125 Decoled Spiral Clear | Xenonkungen<\/title>\n<meta name=\"description\" content=\"LED-lampa E27 G125 Decoled Spiral Clear 3-step memory - 4.0w - 2100K - 3-Step-Dim (Memory) \u2013 Snabb leverans, \u00f6ppet k\u00f6p 30 dagar.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xenonkungen.com\/es\/producto\/lampara-led-e27-g125-espiral-transparente-memoria-de-3-niveles-40-w-2100-k-memoria-de-atenuacion-de-3-niveles\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LED-lampa E27 G125 Decoled Spiral Clear | Xenonkungen\" \/>\n<meta property=\"og:description\" content=\"LED-lampa E27 G125 Decoled Spiral Clear 3-step memory - 4.0w - 2100K - 3-Step-Dim (Memory) \u2013 Snabb leverans, \u00f6ppet k\u00f6p 30 dagar.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xenonkungen.com\/es\/producto\/lampara-led-e27-g125-espiral-transparente-memoria-de-3-niveles-40-w-2100-k-memoria-de-atenuacion-de-3-niveles\/\" \/>\n<meta property=\"og:site_name\" content=\"Xenonkungen\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-07T13:43:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/05\/lk-354-89-1_MN.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/xenonkungen.com\/produkt\/led-lampa-e27-g125-decoled-spiral-clear-3-step-memory-4-0w-2100k-3-step-dim-memory\/\",\"url\":\"https:\/\/xenonkungen.com\/produkt\/led-lampa-e27-g125-decoled-spiral-clear-3-step-memory-4-0w-2100k-3-step-dim-memory\/\",\"name\":\"LED-lampa E27 G125 Decoled Spiral Clear | Xenonkungen\",\"isPartOf\":{\"@id\":\"https:\/\/xenonkungen.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/xenonkungen.com\/produkt\/led-lampa-e27-g125-decoled-spiral-clear-3-step-memory-4-0w-2100k-3-step-dim-memory\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/xenonkungen.com\/produkt\/led-lampa-e27-g125-decoled-spiral-clear-3-step-memory-4-0w-2100k-3-step-dim-memory\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/05\/lk-354-89-1_MN.jpg\",\"datePublished\":\"2026-05-19T19:19:54+00:00\",\"dateModified\":\"2026-07-07T13:43:01+00:00\",\"description\":\"LED-lampa E27 G125 Decoled Spiral Clear 3-step memory - 4.0w - 2100K - 3-Step-Dim (Memory) \u2013 Snabb leverans, \u00f6ppet k\u00f6p 30 dagar.\",\"breadcrumb\":{\"@id\":\"https:\/\/xenonkungen.com\/produkt\/led-lampa-e27-g125-decoled-spiral-clear-3-step-memory-4-0w-2100k-3-step-dim-memory\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/xenonkungen.com\/produkt\/led-lampa-e27-g125-decoled-spiral-clear-3-step-memory-4-0w-2100k-3-step-dim-memory\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/xenonkungen.com\/produkt\/led-lampa-e27-g125-decoled-spiral-clear-3-step-memory-4-0w-2100k-3-step-dim-memory\/#primaryimage\",\"url\":\"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/05\/lk-354-89-1_MN.jpg\",\"contentUrl\":\"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/05\/lk-354-89-1_MN.jpg\",\"width\":1600,\"height\":1600,\"caption\":\"IMPORT_LEDKUNGEN\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/xenonkungen.com\/produkt\/led-lampa-e27-g125-decoled-spiral-clear-3-step-memory-4-0w-2100k-3-step-dim-memory\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hem\",\"item\":\"https:\/\/xenonkungen.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/xenonkungen.com\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"LED-lampa E27 G125 Decoled Spiral Clear 3-step memory &#8211; 4.0w &#8211; 2100K &#8211; 3-Step-Dim (Memory) &#8211; Star Trading\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/xenonkungen.com\/#website\",\"url\":\"https:\/\/xenonkungen.com\/\",\"name\":\"Xenonkungen\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/xenonkungen.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u00e1mpara LED E27 G125 Decoled Spiral Clear | The Xenon King","description":"Bombilla LED E27 G125 Decoled Spiral Clear con memoria de 3 niveles - 4,0 W - 2100 K - Atenuaci\u00f3n de 3 niveles (memoria) - Entrega r\u00e1pida, plazo de compra de 30 d\u00edas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xenonkungen.com\/es\/producto\/lampara-led-e27-g125-espiral-transparente-memoria-de-3-niveles-40-w-2100-k-memoria-de-atenuacion-de-3-niveles\/","og_locale":"es_ES","og_type":"article","og_title":"LED-lampa E27 G125 Decoled Spiral Clear | Xenonkungen","og_description":"LED-lampa E27 G125 Decoled Spiral Clear 3-step memory - 4.0w - 2100K - 3-Step-Dim (Memory) \u2013 Snabb leverans, \u00f6ppet k\u00f6p 30 dagar.","og_url":"https:\/\/xenonkungen.com\/es\/producto\/lampara-led-e27-g125-espiral-transparente-memoria-de-3-niveles-40-w-2100-k-memoria-de-atenuacion-de-3-niveles\/","og_site_name":"Xenonkungen","article_modified_time":"2026-07-07T13:43:01+00:00","og_image":[{"width":1600,"height":1600,"url":"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/05\/lk-354-89-1_MN.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/xenonkungen.com\/produkt\/led-lampa-e27-g125-decoled-spiral-clear-3-step-memory-4-0w-2100k-3-step-dim-memory\/","url":"https:\/\/xenonkungen.com\/produkt\/led-lampa-e27-g125-decoled-spiral-clear-3-step-memory-4-0w-2100k-3-step-dim-memory\/","name":"L\u00e1mpara LED E27 G125 Decoled Spiral Clear | The Xenon King","isPartOf":{"@id":"https:\/\/xenonkungen.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/xenonkungen.com\/produkt\/led-lampa-e27-g125-decoled-spiral-clear-3-step-memory-4-0w-2100k-3-step-dim-memory\/#primaryimage"},"image":{"@id":"https:\/\/xenonkungen.com\/produkt\/led-lampa-e27-g125-decoled-spiral-clear-3-step-memory-4-0w-2100k-3-step-dim-memory\/#primaryimage"},"thumbnailUrl":"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/05\/lk-354-89-1_MN.jpg","datePublished":"2026-05-19T19:19:54+00:00","dateModified":"2026-07-07T13:43:01+00:00","description":"Bombilla LED E27 G125 Decoled Spiral Clear con memoria de 3 niveles - 4,0 W - 2100 K - Atenuaci\u00f3n de 3 niveles (memoria) - Entrega r\u00e1pida, plazo de compra de 30 d\u00edas.","breadcrumb":{"@id":"https:\/\/xenonkungen.com\/produkt\/led-lampa-e27-g125-decoled-spiral-clear-3-step-memory-4-0w-2100k-3-step-dim-memory\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xenonkungen.com\/produkt\/led-lampa-e27-g125-decoled-spiral-clear-3-step-memory-4-0w-2100k-3-step-dim-memory\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/xenonkungen.com\/produkt\/led-lampa-e27-g125-decoled-spiral-clear-3-step-memory-4-0w-2100k-3-step-dim-memory\/#primaryimage","url":"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/05\/lk-354-89-1_MN.jpg","contentUrl":"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/05\/lk-354-89-1_MN.jpg","width":1600,"height":1600,"caption":"IMPORT_LEDKUNGEN"},{"@type":"BreadcrumbList","@id":"https:\/\/xenonkungen.com\/produkt\/led-lampa-e27-g125-decoled-spiral-clear-3-step-memory-4-0w-2100k-3-step-dim-memory\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hem","item":"https:\/\/xenonkungen.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/xenonkungen.com\/shop\/"},{"@type":"ListItem","position":3,"name":"LED-lampa E27 G125 Decoled Spiral Clear 3-step memory &#8211; 4.0w &#8211; 2100K &#8211; 3-Step-Dim (Memory) &#8211; Star Trading"}]},{"@type":"WebSite","@id":"https:\/\/xenonkungen.com\/#website","url":"https:\/\/xenonkungen.com\/","name":"Xenonkungen","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xenonkungen.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"taxonomy_info":{"anvandningsomrade":[{"value":3288,"label":"Hem"}],"product_cat":[{"value":3104,"label":"Dekorativa E-lampor"},{"value":3093,"label":"E27-lampor"}],"pa_fuktskydd-varde-ipxx":[{"value":1993,"label":"IP20"}],"pa_lampsockel-kontakt":[{"value":3193,"label":"E27"}]},"featured_image_src_large":["https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/05\/lk-354-89-1_MN-1024x1024.jpg",1024,1024,true],"author_info":[],"comment_info":0,"_links":{"self":[{"href":"https:\/\/xenonkungen.com\/es\/wp-json\/wp\/v2\/product\/31971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xenonkungen.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/xenonkungen.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/xenonkungen.com\/es\/wp-json\/wp\/v2\/comments?post=31971"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xenonkungen.com\/es\/wp-json\/wp\/v2\/media\/31969"}],"wp:attachment":[{"href":"https:\/\/xenonkungen.com\/es\/wp-json\/wp\/v2\/media?parent=31971"}],"wp:term":[{"taxonomy":"anvandningsomrade","embeddable":true,"href":"https:\/\/xenonkungen.com\/es\/wp-json\/wp\/v2\/anvandningsomrade?post=31971"},{"taxonomy":"bilmarken","embeddable":true,"href":"https:\/\/xenonkungen.com\/es\/wp-json\/wp\/v2\/bilmarken?post=31971"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/xenonkungen.com\/es\/wp-json\/wp\/v2\/product_brand?post=31971"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/xenonkungen.com\/es\/wp-json\/wp\/v2\/product_cat?post=31971"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/xenonkungen.com\/es\/wp-json\/wp\/v2\/product_tag?post=31971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}