{"id":28082,"date":"2026-03-18T08:42:27","date_gmt":"2026-03-18T07:42:27","guid":{"rendered":"https:\/\/xenonkungen.com\/?post_type=product&#038;p=28082"},"modified":"2026-05-12T14:46:09","modified_gmt":"2026-05-12T13:46:09","slug":"tershine-droogdoek-klein-50x55","status":"publish","type":"product","link":"https:\/\/xenonkungen.com\/nl\/product\/tershine-droogdoek-klein-50x55\/","title":{"rendered":"Tershine handdoek \u2013 klein 50\u00d755"},"content":{"rendered":"<p>Veelzijdig microvezeldoekje van zeer hoge kwaliteit met een enorm absorptievermogen. Werkt net zo goed op lakwerk als op glas, of waarom niet in het interieur van uw auto?<\/p>\n<p><strong>Zeer effectief<br \/>\nOok perfect voor in uw voertuig.<\/strong><strong><br \/>\nWreed voor glas en spiegels<br \/>\nZacht voor het oppervlak<br \/>\nKan steeds opnieuw gewassen worden.<br \/>\nPerfect voor auto, boot, camper, caravan, vrachtwagen, motorfiets<br \/>\nWerkt net zo goed om je natte huisdier af te drogen na een wandeling.<\/strong><\/p>\n<p>Ruitenwisser model Tokbra! Uitstekende absorptie en zeer zacht voor de lak. Werkt ook perfect voor binnen en op de ruiten.<\/p>\n<p><strong>GSM:<\/strong>\u00a0530<br \/>\n<strong>Grootte:<\/strong>\u00a050\u00d755 cm<br \/>\n<strong>Materiaal:<\/strong>\u00a080% Polyester, 20% Polyamide<\/p>\n<p><strong>Onderhoudsinstructies:<\/strong>\u00a0Was op 40 graden zonder wasverzachter. Gebruik geen gewoon wasmiddel, want dat kan de vezels &#039;sluiten&#039; en de kleding daardoor minder goed wassen. Gebruik Refresh - Fiber Wash of APC\/Alkaline (een beetje kurk in de wasmachine) en dat werkt meestal prima.<\/p>","protected":false},"excerpt":{"rendered":"<p>Veelzijdig microvezeldoekje van zeer hoge kwaliteit met een enorm absorptievermogen.<\/p>","protected":false},"featured_media":28084,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_smort_price_nok":"","_smort_price_dkk":"","_smort_price_eur":"","_smort_sale_price_nok":"","_smort_sale_price_dkk":"","_smort_sale_price_eur":"","smort_restorder":"","shipmondo_restorder":"","_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","smort_custom_pricelist_1":"88.96","smort_custom_pricelist_2":"88.96","smort_custom_pricelist_3":"88.96","smort_custom_pricelist_4":"111.2","smort_custom_pricelist_5":"88.96"},"anvandningsomrade":[],"bilmarken":[],"product_brand":[2893],"product_cat":[2450,378],"product_tag":[],"class_list":{"0":"post-28082","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-tershine","7":"product_cat-tillbehor-bilvard","8":"product_cat-bilvard","10":"first","11":"onbackorder","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"bundled_by":[],"bundle_stock_status":"onbackorder","bundle_stock_quantity":0,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tershine Torkduk - Small 50x55 - Xenonkungen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xenonkungen.com\/nl\/product\/tershine-droogdoek-klein-50x55\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tershine Torkduk - Small 50x55 - Xenonkungen\" \/>\n<meta property=\"og:description\" content=\"M\u00e5ngsidig torkduk i mikrofiber av mycket h\u00f6g kvalitet med enorm uppsugningsf\u00f6rm\u00e5ga.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xenonkungen.com\/nl\/product\/tershine-droogdoek-klein-50x55\/\" \/>\n<meta property=\"og:site_name\" content=\"Xenonkungen\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T13:46:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/03\/uw8Bfmcia6sRNIMU3xPFDaILMGDte13XVOEkK89q.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/xenonkungen.com\/produkt\/tershine-torkduk-small-50x55\/\",\"url\":\"https:\/\/xenonkungen.com\/produkt\/tershine-torkduk-small-50x55\/\",\"name\":\"Tershine Torkduk - Small 50x55 - Xenonkungen\",\"isPartOf\":{\"@id\":\"https:\/\/xenonkungen.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/xenonkungen.com\/produkt\/tershine-torkduk-small-50x55\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/xenonkungen.com\/produkt\/tershine-torkduk-small-50x55\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/03\/uw8Bfmcia6sRNIMU3xPFDaILMGDte13XVOEkK89q.webp\",\"datePublished\":\"2026-03-18T07:42:27+00:00\",\"dateModified\":\"2026-05-12T13:46:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/xenonkungen.com\/produkt\/tershine-torkduk-small-50x55\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/xenonkungen.com\/produkt\/tershine-torkduk-small-50x55\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/xenonkungen.com\/produkt\/tershine-torkduk-small-50x55\/#primaryimage\",\"url\":\"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/03\/uw8Bfmcia6sRNIMU3xPFDaILMGDte13XVOEkK89q.webp\",\"contentUrl\":\"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/03\/uw8Bfmcia6sRNIMU3xPFDaILMGDte13XVOEkK89q.webp\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/xenonkungen.com\/produkt\/tershine-torkduk-small-50x55\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hem\",\"item\":\"https:\/\/xenonkungen.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/xenonkungen.com\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tershine Torkduk &#8211; Small 50&#215;55\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/xenonkungen.com\/#website\",\"url\":\"https:\/\/xenonkungen.com\/\",\"name\":\"Xenonkungen\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/xenonkungen.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tershine Handdoek - Klein 50x55 - De Xenon Koning","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xenonkungen.com\/nl\/product\/tershine-droogdoek-klein-50x55\/","og_locale":"nl_NL","og_type":"article","og_title":"Tershine Torkduk - Small 50x55 - Xenonkungen","og_description":"M\u00e5ngsidig torkduk i mikrofiber av mycket h\u00f6g kvalitet med enorm uppsugningsf\u00f6rm\u00e5ga.","og_url":"https:\/\/xenonkungen.com\/nl\/product\/tershine-droogdoek-klein-50x55\/","og_site_name":"Xenonkungen","article_modified_time":"2026-05-12T13:46:09+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/03\/uw8Bfmcia6sRNIMU3xPFDaILMGDte13XVOEkK89q.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"1 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/xenonkungen.com\/produkt\/tershine-torkduk-small-50x55\/","url":"https:\/\/xenonkungen.com\/produkt\/tershine-torkduk-small-50x55\/","name":"Tershine Handdoek - Klein 50x55 - De Xenon Koning","isPartOf":{"@id":"https:\/\/xenonkungen.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/xenonkungen.com\/produkt\/tershine-torkduk-small-50x55\/#primaryimage"},"image":{"@id":"https:\/\/xenonkungen.com\/produkt\/tershine-torkduk-small-50x55\/#primaryimage"},"thumbnailUrl":"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/03\/uw8Bfmcia6sRNIMU3xPFDaILMGDte13XVOEkK89q.webp","datePublished":"2026-03-18T07:42:27+00:00","dateModified":"2026-05-12T13:46:09+00:00","breadcrumb":{"@id":"https:\/\/xenonkungen.com\/produkt\/tershine-torkduk-small-50x55\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xenonkungen.com\/produkt\/tershine-torkduk-small-50x55\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/xenonkungen.com\/produkt\/tershine-torkduk-small-50x55\/#primaryimage","url":"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/03\/uw8Bfmcia6sRNIMU3xPFDaILMGDte13XVOEkK89q.webp","contentUrl":"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/03\/uw8Bfmcia6sRNIMU3xPFDaILMGDte13XVOEkK89q.webp","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/xenonkungen.com\/produkt\/tershine-torkduk-small-50x55\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hem","item":"https:\/\/xenonkungen.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/xenonkungen.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Tershine Torkduk &#8211; Small 50&#215;55"}]},{"@type":"WebSite","@id":"https:\/\/xenonkungen.com\/#website","url":"https:\/\/xenonkungen.com\/","name":"Xenonkungen","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xenonkungen.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"taxonomy_info":{"product_brand":[{"value":2893,"label":"Tershine"}],"product_cat":[{"value":2450,"label":"6 | Tillbeh\u00f6r"},{"value":378,"label":"Bilv\u00e5rd"}]},"featured_image_src_large":["https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/03\/uw8Bfmcia6sRNIMU3xPFDaILMGDte13XVOEkK89q.webp",1024,1024,false],"author_info":[],"comment_info":0,"_links":{"self":[{"href":"https:\/\/xenonkungen.com\/nl\/wp-json\/wp\/v2\/product\/28082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xenonkungen.com\/nl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/xenonkungen.com\/nl\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/xenonkungen.com\/nl\/wp-json\/wp\/v2\/comments?post=28082"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xenonkungen.com\/nl\/wp-json\/wp\/v2\/media\/28084"}],"wp:attachment":[{"href":"https:\/\/xenonkungen.com\/nl\/wp-json\/wp\/v2\/media?parent=28082"}],"wp:term":[{"taxonomy":"anvandningsomrade","embeddable":true,"href":"https:\/\/xenonkungen.com\/nl\/wp-json\/wp\/v2\/anvandningsomrade?post=28082"},{"taxonomy":"bilmarken","embeddable":true,"href":"https:\/\/xenonkungen.com\/nl\/wp-json\/wp\/v2\/bilmarken?post=28082"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/xenonkungen.com\/nl\/wp-json\/wp\/v2\/product_brand?post=28082"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/xenonkungen.com\/nl\/wp-json\/wp\/v2\/product_cat?post=28082"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/xenonkungen.com\/nl\/wp-json\/wp\/v2\/product_tag?post=28082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}