{"id":33642,"date":"2026-05-22T08:35:05","date_gmt":"2026-05-22T07:35:05","guid":{"rendered":"https:\/\/xenonkungen.com\/produkt\/uni-t-multimeter-digital-600v-10mhz-40mohm-uni-t\/"},"modified":"2026-08-27T13:34:54","modified_gmt":"2026-08-27T12:34:54","slug":"uni-t-digitale-multimeter-600v-10mhz-40mohm-uni-t","status":"publish","type":"product","link":"https:\/\/xenonkungen.com\/nl\/product\/uni-t-digitale-multimeter-600v-10mhz-40mohm-uni-t\/","title":{"rendered":"UNI-T \u2013 Digitale multimeter 600V 10MHz 40MOhm \u2013 UNI-T"},"content":{"rendered":"<h2>UNI-T \u2013 Digitale multimeter 600V 10MHz 40MOhm \u2013 UNI<\/h2>\n<p>Multimeter \u2013 Veelzijdig en nauwkeurig elektrisch gereedschap voor alle toepassingen Tekst: Een multimeter is een onmisbaar hulpmiddel voor iedereen die met elektrische systemen werkt. Met een multimeter kunt u spanning, stroom, weerstand en nog veel meer meten en bewaken. Onze multimeters zijn ontworpen met de nadruk op precisie, betrouwbaarheid en gebruiksgemak. Onze multimeter is uitgerust met geavanceerde technologie die nauwkeurige metingen garandeert.<\/p>\n<h2>Koop UNI-T bij Xenonkungen<\/h2>\n<p>Snelle levering en 30 dagen bedenktijd.<\/p>","protected":false},"excerpt":{"rendered":"<p>UNI-T \u2013 Digitale multimeter 600V 10MHz 40MOhm \u2013 UNI-T<\/p>","protected":false},"featured_media":33641,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_smort_price_nok":"","_smort_price_dkk":"","_smort_price_eur":"31.73","_smort_sale_price_nok":"","_smort_sale_price_dkk":"","_smort_sale_price_eur":"","smort_restorder":"","shipmondo_restorder":"","_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","smort_custom_pricelist_1":"223.36","smort_custom_pricelist_2":"195.44","smort_custom_pricelist_3":"195.44","smort_custom_pricelist_4":"279.2","smort_custom_pricelist_5":"195.44"},"anvandningsomrade":[3288],"bilmarken":[],"product_brand":[],"product_cat":[2986],"product_tag":[],"class_list":["post-33642","product","type-product","status-publish","has-post-thumbnail","anvandningsomrade-hem","product_cat-bilvard-och-tillbehor","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":1,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>UNI-T - Multimeter digital 600V 10MHz 40MOhm - UNI | Xenonkungen<\/title>\n<meta name=\"description\" content=\"UNI-T - Multimeter digital 600V 10MHz 40MOhm - UNI-T. Snabb leverans, \u00f6ppet k\u00f6p 30 dagar.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xenonkungen.com\/nl\/product\/uni-t-digitale-multimeter-600v-10mhz-40mohm-uni-t\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UNI-T - Multimeter digital 600V 10MHz 40MOhm - UNI | Xenonkungen\" \/>\n<meta property=\"og:description\" content=\"UNI-T - Multimeter digital 600V 10MHz 40MOhm - UNI-T. Snabb leverans, \u00f6ppet k\u00f6p 30 dagar.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xenonkungen.com\/nl\/product\/uni-t-digitale-multimeter-600v-10mhz-40mohm-uni-t\/\" \/>\n<meta property=\"og:site_name\" content=\"Xenonkungen\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-27T12:34:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/05\/lk-23023_MN.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"799\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/xenonkungen.com\/produkt\/uni-t-multimeter-digital-600v-10mhz-40mohm-uni-t\/\",\"url\":\"https:\/\/xenonkungen.com\/produkt\/uni-t-multimeter-digital-600v-10mhz-40mohm-uni-t\/\",\"name\":\"UNI-T - Multimeter digital 600V 10MHz 40MOhm - UNI | Xenonkungen\",\"isPartOf\":{\"@id\":\"https:\/\/xenonkungen.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/xenonkungen.com\/produkt\/uni-t-multimeter-digital-600v-10mhz-40mohm-uni-t\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/xenonkungen.com\/produkt\/uni-t-multimeter-digital-600v-10mhz-40mohm-uni-t\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/05\/lk-23023_MN.png\",\"datePublished\":\"2026-05-22T07:35:05+00:00\",\"dateModified\":\"2026-08-27T12:34:54+00:00\",\"description\":\"UNI-T - Multimeter digital 600V 10MHz 40MOhm - UNI-T. Snabb leverans, \u00f6ppet k\u00f6p 30 dagar.\",\"breadcrumb\":{\"@id\":\"https:\/\/xenonkungen.com\/produkt\/uni-t-multimeter-digital-600v-10mhz-40mohm-uni-t\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/xenonkungen.com\/produkt\/uni-t-multimeter-digital-600v-10mhz-40mohm-uni-t\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/xenonkungen.com\/produkt\/uni-t-multimeter-digital-600v-10mhz-40mohm-uni-t\/#primaryimage\",\"url\":\"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/05\/lk-23023_MN.png\",\"contentUrl\":\"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/05\/lk-23023_MN.png\",\"width\":800,\"height\":799,\"caption\":\"IMPORT_LEDKUNGEN_PORTABEL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/xenonkungen.com\/produkt\/uni-t-multimeter-digital-600v-10mhz-40mohm-uni-t\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hem\",\"item\":\"https:\/\/xenonkungen.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/xenonkungen.com\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"UNI-T &#8211; Multimeter digital 600V 10MHz 40MOhm &#8211; UNI-T\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/xenonkungen.com\/#website\",\"url\":\"https:\/\/xenonkungen.com\/\",\"name\":\"Xenonkungen\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/xenonkungen.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"UNI-T - Digitale multimeter 600V 10MHz 40MOhm - UNI | De Xenon Koning","description":"UNI-T - Digitale multimeter 600V 10MHz 40MOhm - UNI-T. Snelle levering, 30 dagen bedenktijd.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xenonkungen.com\/nl\/product\/uni-t-digitale-multimeter-600v-10mhz-40mohm-uni-t\/","og_locale":"nl_NL","og_type":"article","og_title":"UNI-T - Multimeter digital 600V 10MHz 40MOhm - UNI | Xenonkungen","og_description":"UNI-T - Multimeter digital 600V 10MHz 40MOhm - UNI-T. Snabb leverans, \u00f6ppet k\u00f6p 30 dagar.","og_url":"https:\/\/xenonkungen.com\/nl\/product\/uni-t-digitale-multimeter-600v-10mhz-40mohm-uni-t\/","og_site_name":"Xenonkungen","article_modified_time":"2026-08-27T12:34:54+00:00","og_image":[{"width":800,"height":799,"url":"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/05\/lk-23023_MN.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/xenonkungen.com\/produkt\/uni-t-multimeter-digital-600v-10mhz-40mohm-uni-t\/","url":"https:\/\/xenonkungen.com\/produkt\/uni-t-multimeter-digital-600v-10mhz-40mohm-uni-t\/","name":"UNI-T - Digitale multimeter 600V 10MHz 40MOhm - UNI | De Xenon Koning","isPartOf":{"@id":"https:\/\/xenonkungen.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/xenonkungen.com\/produkt\/uni-t-multimeter-digital-600v-10mhz-40mohm-uni-t\/#primaryimage"},"image":{"@id":"https:\/\/xenonkungen.com\/produkt\/uni-t-multimeter-digital-600v-10mhz-40mohm-uni-t\/#primaryimage"},"thumbnailUrl":"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/05\/lk-23023_MN.png","datePublished":"2026-05-22T07:35:05+00:00","dateModified":"2026-08-27T12:34:54+00:00","description":"UNI-T - Digitale multimeter 600V 10MHz 40MOhm - UNI-T. Snelle levering, 30 dagen bedenktijd.","breadcrumb":{"@id":"https:\/\/xenonkungen.com\/produkt\/uni-t-multimeter-digital-600v-10mhz-40mohm-uni-t\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xenonkungen.com\/produkt\/uni-t-multimeter-digital-600v-10mhz-40mohm-uni-t\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/xenonkungen.com\/produkt\/uni-t-multimeter-digital-600v-10mhz-40mohm-uni-t\/#primaryimage","url":"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/05\/lk-23023_MN.png","contentUrl":"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/05\/lk-23023_MN.png","width":800,"height":799,"caption":"IMPORT_LEDKUNGEN_PORTABEL"},{"@type":"BreadcrumbList","@id":"https:\/\/xenonkungen.com\/produkt\/uni-t-multimeter-digital-600v-10mhz-40mohm-uni-t\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hem","item":"https:\/\/xenonkungen.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/xenonkungen.com\/shop\/"},{"@type":"ListItem","position":3,"name":"UNI-T &#8211; Multimeter digital 600V 10MHz 40MOhm &#8211; UNI-T"}]},{"@type":"WebSite","@id":"https:\/\/xenonkungen.com\/#website","url":"https:\/\/xenonkungen.com\/","name":"Xenonkungen","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xenonkungen.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"taxonomy_info":{"anvandningsomrade":[{"value":3288,"label":"Hem"}],"product_cat":[{"value":2986,"label":"Bilv\u00e5rd &amp; Tillbeh\u00f6r"}]},"featured_image_src_large":["https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/05\/lk-23023_MN.png",800,799,false],"author_info":[],"comment_info":0,"_links":{"self":[{"href":"https:\/\/xenonkungen.com\/nl\/wp-json\/wp\/v2\/product\/33642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xenonkungen.com\/nl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/xenonkungen.com\/nl\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/xenonkungen.com\/nl\/wp-json\/wp\/v2\/comments?post=33642"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xenonkungen.com\/nl\/wp-json\/wp\/v2\/media\/33641"}],"wp:attachment":[{"href":"https:\/\/xenonkungen.com\/nl\/wp-json\/wp\/v2\/media?parent=33642"}],"wp:term":[{"taxonomy":"anvandningsomrade","embeddable":true,"href":"https:\/\/xenonkungen.com\/nl\/wp-json\/wp\/v2\/anvandningsomrade?post=33642"},{"taxonomy":"bilmarken","embeddable":true,"href":"https:\/\/xenonkungen.com\/nl\/wp-json\/wp\/v2\/bilmarken?post=33642"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/xenonkungen.com\/nl\/wp-json\/wp\/v2\/product_brand?post=33642"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/xenonkungen.com\/nl\/wp-json\/wp\/v2\/product_cat?post=33642"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/xenonkungen.com\/nl\/wp-json\/wp\/v2\/product_tag?post=33642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}