{"id":4585,"date":"2025-04-15T09:14:54","date_gmt":"2025-04-15T09:14:54","guid":{"rendered":"https:\/\/xenonkungen.com\/product\/meguiars-perfect-clarity-glass-sealent\/"},"modified":"2026-05-08T13:22:53","modified_gmt":"2026-05-08T12:22:53","slug":"meguiars-perfect-clarity-glasverzegeling","status":"publish","type":"product","link":"https:\/\/xenonkungen.com\/nl\/product\/meguiars-perfect-clarity-glasverzegeling\/","title":{"rendered":"Meguiar's Perfect Clarity Glass Sealent"},"content":{"rendered":"<h1>Perfecte Helderheid Glass Sealent<\/h1>\n<p>Superhydrofobische formule die water van het oppervlak afstoot. Vergemakkelijkt het rijden en het zicht bij regenachtig weer. Maakt het in de winter gemakkelijker om de voorruit van ijs en rijp te ontdoen.<\/p>\n<p>Reinig het raam met bijv,<span>\u00a0<\/span><a href=\"https:\/\/www.xenonkungen.com\/se\/produkter\/bilvard\/ovriga-ytor\/perfect-clarity-glass-polishing-compound.html\">Perfecte helderheid polijstpasta voor glas<\/a><span>\u00a0<\/span>voor betere hechting<\/p>\n<p><strong>Inhoud (ml):<\/strong> 118<\/p>\n<h2><strong>Waarschuwing!<\/strong><\/h2>\n<p><strong>Kleurcodering:<\/strong><\/p>\n<ul>\n<li>Licht ontvlambare vloeistof en damp<\/li>\n<li>Kan dodelijk zijn als het wordt ingeslikt en in de luchtwegen terechtkomt<\/li>\n<li>Veroorzaakt ernstige oogirritatie<\/li>\n<li>Kan je slaperig of duizelig maken<\/li>\n<li>Nadelige effecten op lange termijn op waterorganismen<\/li>\n<\/ul>\n<p><strong>Beschermende aanduidingen:<\/strong><\/p>\n<ul>\n<li>Houd de verpakking of het etiket bij de hand voor het geval je medische hulp nodig hebt<\/li>\n<li>Buiten bereik van kinderen bewaren<\/li>\n<li>Mag niet worden blootgesteld aan hitte, hete oppervlakken, vonken, open vuur en andere ontstekingsbronnen. Roken is verboden<\/li>\n<li>Alleen buiten of op goed geventileerde plaatsen gebruiken<\/li>\n<li>NA INSLIKKEN: Onmiddellijk contact opnemen met het ANTIGIFCENTRUM of een arts.<\/li>\n<li>NIET laten braken<\/li>\n<li>Op een goed geventileerde plaats bewaren. Op een koele plaats bewaren<\/li>\n<li>Achter slot en grendel<\/li>\n<li>De inhoud\/container wordt afgevoerd in overeenstemming met de nationale regelgeving<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Een product dat water en vuil van autoruiten afstoot.<\/p>","protected":false},"featured_media":4586,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_smort_price_nok":"180","_smort_price_dkk":"155","_smort_price_eur":"20.82","_smort_sale_price_nok":"180","_smort_sale_price_dkk":"","_smort_sale_price_eur":"","smort_restorder":"","shipmondo_restorder":"","_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","smort_custom_pricelist_1":"146.56","smort_custom_pricelist_2":"146.56","smort_custom_pricelist_3":"139.23","smort_custom_pricelist_4":"183.2","smort_custom_pricelist_5":"146.56"},"anvandningsomrade":[],"bilmarken":[],"product_brand":[1383],"product_cat":[2618,378,1402],"product_tag":[],"class_list":{"0":"post-4585","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-meguiars","7":"product_cat-interior","8":"product_cat-bilvard","9":"product_cat-outlet","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":1,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Meguiar&#039;s Perfect Clarity Glass Sealent - Xenonkungen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xenonkungen.com\/nl\/product\/meguiars-perfect-clarity-glasverzegeling\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Meguiar&#039;s Perfect Clarity Glass Sealent - Xenonkungen\" \/>\n<meta property=\"og:description\" content=\"En produkt som st\u00f6ter bort vatten och smuts fr\u00e5n vindrutor.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xenonkungen.com\/nl\/product\/meguiars-perfect-clarity-glasverzegeling\/\" \/>\n<meta property=\"og:site_name\" content=\"Xenonkungen\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T12:22:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/xenonkungen.com\/wp-content\/uploads\/2025\/04\/190088119-origpic-b32312.png\" \/>\n\t<meta property=\"og:image:width\" content=\"432\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/xenonkungen.com\/produkt\/meguiars-perfect-clarity-glass-sealent\/\",\"url\":\"https:\/\/xenonkungen.com\/produkt\/meguiars-perfect-clarity-glass-sealent\/\",\"name\":\"Meguiar's Perfect Clarity Glass Sealent - Xenonkungen\",\"isPartOf\":{\"@id\":\"https:\/\/xenonkungen.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/xenonkungen.com\/produkt\/meguiars-perfect-clarity-glass-sealent\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/xenonkungen.com\/produkt\/meguiars-perfect-clarity-glass-sealent\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/xenonkungen.com\/wp-content\/uploads\/2025\/04\/190088119-origpic-b32312.png\",\"datePublished\":\"2025-04-15T09:14:54+00:00\",\"dateModified\":\"2026-05-08T12:22:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/xenonkungen.com\/produkt\/meguiars-perfect-clarity-glass-sealent\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/xenonkungen.com\/produkt\/meguiars-perfect-clarity-glass-sealent\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/xenonkungen.com\/produkt\/meguiars-perfect-clarity-glass-sealent\/#primaryimage\",\"url\":\"https:\/\/xenonkungen.com\/wp-content\/uploads\/2025\/04\/190088119-origpic-b32312.png\",\"contentUrl\":\"https:\/\/xenonkungen.com\/wp-content\/uploads\/2025\/04\/190088119-origpic-b32312.png\",\"width\":432,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/xenonkungen.com\/produkt\/meguiars-perfect-clarity-glass-sealent\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hem\",\"item\":\"https:\/\/xenonkungen.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/xenonkungen.com\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Meguiar&#8217;s Perfect Clarity Glass Sealent\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/xenonkungen.com\/#website\",\"url\":\"https:\/\/xenonkungen.com\/\",\"name\":\"Xenonkungen\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/xenonkungen.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Meguiar&#039;s Perfect Clarity Glasafdichtingsmiddel - De Xenon Koning","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xenonkungen.com\/nl\/product\/meguiars-perfect-clarity-glasverzegeling\/","og_locale":"nl_NL","og_type":"article","og_title":"Meguiar's Perfect Clarity Glass Sealent - Xenonkungen","og_description":"En produkt som st\u00f6ter bort vatten och smuts fr\u00e5n vindrutor.","og_url":"https:\/\/xenonkungen.com\/nl\/product\/meguiars-perfect-clarity-glasverzegeling\/","og_site_name":"Xenonkungen","article_modified_time":"2026-05-08T12:22:53+00:00","og_image":[{"width":432,"height":1000,"url":"https:\/\/xenonkungen.com\/wp-content\/uploads\/2025\/04\/190088119-origpic-b32312.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"1 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/xenonkungen.com\/produkt\/meguiars-perfect-clarity-glass-sealent\/","url":"https:\/\/xenonkungen.com\/produkt\/meguiars-perfect-clarity-glass-sealent\/","name":"Meguiar&#039;s Perfect Clarity Glasafdichtingsmiddel - De Xenon Koning","isPartOf":{"@id":"https:\/\/xenonkungen.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/xenonkungen.com\/produkt\/meguiars-perfect-clarity-glass-sealent\/#primaryimage"},"image":{"@id":"https:\/\/xenonkungen.com\/produkt\/meguiars-perfect-clarity-glass-sealent\/#primaryimage"},"thumbnailUrl":"https:\/\/xenonkungen.com\/wp-content\/uploads\/2025\/04\/190088119-origpic-b32312.png","datePublished":"2025-04-15T09:14:54+00:00","dateModified":"2026-05-08T12:22:53+00:00","breadcrumb":{"@id":"https:\/\/xenonkungen.com\/produkt\/meguiars-perfect-clarity-glass-sealent\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xenonkungen.com\/produkt\/meguiars-perfect-clarity-glass-sealent\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/xenonkungen.com\/produkt\/meguiars-perfect-clarity-glass-sealent\/#primaryimage","url":"https:\/\/xenonkungen.com\/wp-content\/uploads\/2025\/04\/190088119-origpic-b32312.png","contentUrl":"https:\/\/xenonkungen.com\/wp-content\/uploads\/2025\/04\/190088119-origpic-b32312.png","width":432,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/xenonkungen.com\/produkt\/meguiars-perfect-clarity-glass-sealent\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hem","item":"https:\/\/xenonkungen.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/xenonkungen.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Meguiar&#8217;s Perfect Clarity Glass Sealent"}]},{"@type":"WebSite","@id":"https:\/\/xenonkungen.com\/#website","url":"https:\/\/xenonkungen.com\/","name":"Xenonkungen","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xenonkungen.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"taxonomy_info":{"product_brand":[{"value":1383,"label":"Meguiar's"}],"product_cat":[{"value":2618,"label":"Interi\u00f6r"},{"value":378,"label":"Bilv\u00e5rd"},{"value":1402,"label":"Outlet"}]},"featured_image_src_large":["https:\/\/xenonkungen.com\/wp-content\/uploads\/2025\/04\/190088119-origpic-b32312.png",432,1000,false],"author_info":[],"comment_info":0,"_links":{"self":[{"href":"https:\/\/xenonkungen.com\/nl\/wp-json\/wp\/v2\/product\/4585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xenonkungen.com\/nl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/xenonkungen.com\/nl\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/xenonkungen.com\/nl\/wp-json\/wp\/v2\/comments?post=4585"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xenonkungen.com\/nl\/wp-json\/wp\/v2\/media\/4586"}],"wp:attachment":[{"href":"https:\/\/xenonkungen.com\/nl\/wp-json\/wp\/v2\/media?parent=4585"}],"wp:term":[{"taxonomy":"anvandningsomrade","embeddable":true,"href":"https:\/\/xenonkungen.com\/nl\/wp-json\/wp\/v2\/anvandningsomrade?post=4585"},{"taxonomy":"bilmarken","embeddable":true,"href":"https:\/\/xenonkungen.com\/nl\/wp-json\/wp\/v2\/bilmarken?post=4585"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/xenonkungen.com\/nl\/wp-json\/wp\/v2\/product_brand?post=4585"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/xenonkungen.com\/nl\/wp-json\/wp\/v2\/product_cat?post=4585"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/xenonkungen.com\/nl\/wp-json\/wp\/v2\/product_tag?post=4585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}