{"id":7400,"date":"2025-04-15T09:55:06","date_gmt":"2025-04-15T09:55:06","guid":{"rendered":"https:\/\/xenonkungen.com\/product\/h11-night-breaker-laser\/"},"modified":"2026-04-24T17:37:57","modified_gmt":"2026-04-24T16:37:57","slug":"h11-nachtbreker-laser","status":"publish","type":"product","link":"https:\/\/xenonkungen.com\/nl\/product\/h11-nachtbreker-laser\/","title":{"rendered":"H11 Nachtbreker\u00ae-laser"},"content":{"rendered":"<p>NIEUW september 2018! <br \/>Dankzij een innovatieve lasertechnologie schijnen deze lampen tot 150% meer dan standaard halogeenlampen*.<\/p>\n<p>De combinatie van een nieuw ontwikkelde gloeidraad gevuld met zuiver xenongas geeft de lamp extra lichtopbrengst. Dit resulteert in een bereik tot 150 meter en tot 20% witter licht vergeleken met standaardlampen.<\/p>\n<p>Meer licht en dus een betere zichtbaarheid betekent een snellere detectie en reactie op verkeerssituaties.<\/p>\n<p>Lampenkapjes: <strong>H11<\/strong>, PGJ19-2<br \/>Nominaal vermogen: 55W<\/p>\n<p>*) Vergeleken met de minimumvereisten van ECE R112\/R37.<\/p>\n<p>Osram-artikel: 64211NL-HCB<br \/>Productcode: 4052899991873<br \/>Verkocht per paar in harde plastic verpakking.<\/p>\n<div style=\"display: none;\">\n<p>Nachtbreker<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>NIGHT BREAKER LASER - Generatie 2 - De helderste halogeenlamp voor auto's van Osram.<\/p>","protected":false},"featured_media":7401,"comment_status":"closed","ping_status":"open","template":"","meta":{"_acf_changed":false,"_smort_price_nok":"481","_smort_price_dkk":"305","_smort_price_eur":"40.91","_smort_sale_price_nok":"","_smort_sale_price_dkk":"","_smort_sale_price_eur":"","smort_restorder":"","shipmondo_restorder":"","_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","smort_custom_pricelist_1":"288","smort_custom_pricelist_2":"288","smort_custom_pricelist_3":"273.6","smort_custom_pricelist_4":"360","smort_custom_pricelist_5":"288"},"anvandningsomrade":[],"bilmarken":[],"product_brand":[108],"product_cat":[2543,733],"product_tag":[],"class_list":{"0":"post-7400","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-osram","7":"product_cat-halogen-halvljus-helljus","8":"product_cat-halvljus-helljus","9":"pa_faktisk-effekts-forbrukning-841","10":"pa_lampsockel-kontakt-h11","11":"pa_volt-v-159","13":"first","14":"instock","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-simple"},"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":7,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>H11 Night Breaker\u00ae Laser - Xenonkungen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xenonkungen.com\/nl\/product\/h11-nachtbreker-laser\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"H11 Night Breaker\u00ae Laser - Xenonkungen\" \/>\n<meta property=\"og:description\" content=\"NIGHT BREAKER LASER - Generation 2 - Den mest ljusstarka halogenlampan f\u00f6r bilar fr\u00e5n Osram.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xenonkungen.com\/nl\/product\/h11-nachtbreker-laser\/\" \/>\n<meta property=\"og:site_name\" content=\"Xenonkungen\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-24T16:37:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/xenonkungen.com\/wp-content\/uploads\/2025\/04\/160729979-origpic-31e515.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/xenonkungen.com\/produkt\/h11-night-breaker-laser\/\",\"url\":\"https:\/\/xenonkungen.com\/produkt\/h11-night-breaker-laser\/\",\"name\":\"H11 Night Breaker\u00ae Laser - Xenonkungen\",\"isPartOf\":{\"@id\":\"https:\/\/xenonkungen.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/xenonkungen.com\/produkt\/h11-night-breaker-laser\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/xenonkungen.com\/produkt\/h11-night-breaker-laser\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/xenonkungen.com\/wp-content\/uploads\/2025\/04\/160729979-origpic-31e515.jpg\",\"datePublished\":\"2025-04-15T09:55:06+00:00\",\"dateModified\":\"2026-04-24T16:37:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/xenonkungen.com\/produkt\/h11-night-breaker-laser\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/xenonkungen.com\/produkt\/h11-night-breaker-laser\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/xenonkungen.com\/produkt\/h11-night-breaker-laser\/#primaryimage\",\"url\":\"https:\/\/xenonkungen.com\/wp-content\/uploads\/2025\/04\/160729979-origpic-31e515.jpg\",\"contentUrl\":\"https:\/\/xenonkungen.com\/wp-content\/uploads\/2025\/04\/160729979-origpic-31e515.jpg\",\"width\":600,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/xenonkungen.com\/produkt\/h11-night-breaker-laser\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hem\",\"item\":\"https:\/\/xenonkungen.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/xenonkungen.com\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"H11 Night Breaker\u00ae Laser\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/xenonkungen.com\/#website\",\"url\":\"https:\/\/xenonkungen.com\/\",\"name\":\"Xenonkungen\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/xenonkungen.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"H11 Night Breaker\u00ae Laser - De Xenon Koning","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xenonkungen.com\/nl\/product\/h11-nachtbreker-laser\/","og_locale":"nl_NL","og_type":"article","og_title":"H11 Night Breaker\u00ae Laser - Xenonkungen","og_description":"NIGHT BREAKER LASER - Generation 2 - Den mest ljusstarka halogenlampan f\u00f6r bilar fr\u00e5n Osram.","og_url":"https:\/\/xenonkungen.com\/nl\/product\/h11-nachtbreker-laser\/","og_site_name":"Xenonkungen","article_modified_time":"2026-04-24T16:37:57+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/xenonkungen.com\/wp-content\/uploads\/2025\/04\/160729979-origpic-31e515.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/xenonkungen.com\/produkt\/h11-night-breaker-laser\/","url":"https:\/\/xenonkungen.com\/produkt\/h11-night-breaker-laser\/","name":"H11 Night Breaker\u00ae Laser - De Xenon Koning","isPartOf":{"@id":"https:\/\/xenonkungen.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/xenonkungen.com\/produkt\/h11-night-breaker-laser\/#primaryimage"},"image":{"@id":"https:\/\/xenonkungen.com\/produkt\/h11-night-breaker-laser\/#primaryimage"},"thumbnailUrl":"https:\/\/xenonkungen.com\/wp-content\/uploads\/2025\/04\/160729979-origpic-31e515.jpg","datePublished":"2025-04-15T09:55:06+00:00","dateModified":"2026-04-24T16:37:57+00:00","breadcrumb":{"@id":"https:\/\/xenonkungen.com\/produkt\/h11-night-breaker-laser\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xenonkungen.com\/produkt\/h11-night-breaker-laser\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/xenonkungen.com\/produkt\/h11-night-breaker-laser\/#primaryimage","url":"https:\/\/xenonkungen.com\/wp-content\/uploads\/2025\/04\/160729979-origpic-31e515.jpg","contentUrl":"https:\/\/xenonkungen.com\/wp-content\/uploads\/2025\/04\/160729979-origpic-31e515.jpg","width":600,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/xenonkungen.com\/produkt\/h11-night-breaker-laser\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hem","item":"https:\/\/xenonkungen.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/xenonkungen.com\/shop\/"},{"@type":"ListItem","position":3,"name":"H11 Night Breaker\u00ae Laser"}]},{"@type":"WebSite","@id":"https:\/\/xenonkungen.com\/#website","url":"https:\/\/xenonkungen.com\/","name":"Xenonkungen","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xenonkungen.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"taxonomy_info":{"product_brand":[{"value":108,"label":"OSRAM"}],"product_cat":[{"value":2543,"label":"Halogen"},{"value":733,"label":"Halvljus \/ Helljus"}],"pa_faktisk-effekts-forbrukning":[{"value":841,"label":"55"}],"pa_lampsockel-kontakt":[{"value":850,"label":"H11"}],"pa_volt-v":[{"value":159,"label":"12"}]},"featured_image_src_large":["https:\/\/xenonkungen.com\/wp-content\/uploads\/2025\/04\/160729979-origpic-31e515.jpg",600,600,false],"author_info":[],"comment_info":0,"_links":{"self":[{"href":"https:\/\/xenonkungen.com\/nl\/wp-json\/wp\/v2\/product\/7400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xenonkungen.com\/nl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/xenonkungen.com\/nl\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/xenonkungen.com\/nl\/wp-json\/wp\/v2\/comments?post=7400"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xenonkungen.com\/nl\/wp-json\/wp\/v2\/media\/7401"}],"wp:attachment":[{"href":"https:\/\/xenonkungen.com\/nl\/wp-json\/wp\/v2\/media?parent=7400"}],"wp:term":[{"taxonomy":"anvandningsomrade","embeddable":true,"href":"https:\/\/xenonkungen.com\/nl\/wp-json\/wp\/v2\/anvandningsomrade?post=7400"},{"taxonomy":"bilmarken","embeddable":true,"href":"https:\/\/xenonkungen.com\/nl\/wp-json\/wp\/v2\/bilmarken?post=7400"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/xenonkungen.com\/nl\/wp-json\/wp\/v2\/product_brand?post=7400"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/xenonkungen.com\/nl\/wp-json\/wp\/v2\/product_cat?post=7400"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/xenonkungen.com\/nl\/wp-json\/wp\/v2\/product_tag?post=7400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}