{"id":32524,"date":"2026-05-20T08:51:51","date_gmt":"2026-05-20T07:51:51","guid":{"rendered":"https:\/\/xenonkungen.com\/produkt\/led-a60-40w-1800k-e27-ndsrt-amber-1pf\/"},"modified":"2026-07-07T14:57:00","modified_gmt":"2026-07-07T13:57:00","slug":"led-a60-40w-1800k-e27-ndsrt-rav-1pf","status":"publish","type":"product","link":"https:\/\/xenonkungen.com\/no\/produkt\/led-a60-40w-1800k-e27-ndsrt-rav-1pf\/","title":{"rendered":"LED A60 40W 1800K E27 NDSRT Amber 1PF \u2013 Philips"},"content":{"rendered":"<h2>LED A60 40W 1800K E27 NDSRT Amber 1PF<\/h2>\n<p>LED A60 40W 1800K E27 NDSRT Amber 1PF fra Philips. Premium LED-lyskilde for hjem og bedrifter.<\/p>\n<h2>Spesifikasjoner<\/h2>\n<ul>\n<li><strong>Lampefot<\/strong> \u2013 E27<\/li>\n<li><strong>Effekt<\/strong> \u2013 40W<\/li>\n<li><strong>Fargetemperatur<\/strong> \u2013 1800K<\/li>\n<li><strong>Fullf\u00f8r<\/strong> -Rav<\/li>\n<\/ul>\n<h2>Kj\u00f8p Philips hos Xenonkungen<\/h2>\n<p>Autorisert Philips-forhandler. Rask levering og 30-dagers pengene-tilbake-garanti.<\/p>","protected":false},"excerpt":{"rendered":"<p>LED A60 40W 1800K E27 NDSRT Amber 1PF fra Philips. Premium LED-lyskilde.<\/p>","protected":false},"featured_media":32522,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_smort_price_nok":"","_smort_price_dkk":"","_smort_price_eur":"5.36","_smort_sale_price_nok":"","_smort_sale_price_dkk":"","_smort_sale_price_eur":"","smort_restorder":"","shipmondo_restorder":"","_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","smort_custom_pricelist_1":"35.84","smort_custom_pricelist_2":"35.84","smort_custom_pricelist_3":"35.84","smort_custom_pricelist_4":"44.8","smort_custom_pricelist_5":"35.84"},"anvandningsomrade":[3288],"bilmarken":[],"product_brand":[3325],"product_cat":[3093],"product_tag":[],"class_list":["post-32524","product","type-product","status-publish","has-post-thumbnail","anvandningsomrade-hem","product_brand-philips","product_cat-e27-lampor","pa_farg-amber","pa_fuktskydd-varde-ipxx-ip20","pa_lampsockel-kontakt-e27","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":3,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Philips LED A60 40W 1800K E27 NDSRT Amber 1PF | Xenonkungen<\/title>\n<meta name=\"description\" content=\"Philips - LED A60 40W 1800K E27 NDSRT Amber 1PF. Snabb leverans, \u00f6ppet k\u00f6p 30 dagar.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xenonkungen.com\/no\/produkt\/led-a60-40w-1800k-e27-ndsrt-rav-1pf\/\" \/>\n<meta property=\"og:locale\" content=\"nb_NO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Philips LED A60 40W 1800K E27 NDSRT Amber 1PF | Xenonkungen\" \/>\n<meta property=\"og:description\" content=\"Philips - LED A60 40W 1800K E27 NDSRT Amber 1PF. Snabb leverans, \u00f6ppet k\u00f6p 30 dagar.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xenonkungen.com\/no\/produkt\/led-a60-40w-1800k-e27-ndsrt-rav-1pf\/\" \/>\n<meta property=\"og:site_name\" content=\"Xenonkungen\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-07T13:57:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/05\/lk-929003627801_MN.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/xenonkungen.com\/produkt\/led-a60-40w-1800k-e27-ndsrt-amber-1pf\/\",\"url\":\"https:\/\/xenonkungen.com\/produkt\/led-a60-40w-1800k-e27-ndsrt-amber-1pf\/\",\"name\":\"Philips LED A60 40W 1800K E27 NDSRT Amber 1PF | Xenonkungen\",\"isPartOf\":{\"@id\":\"https:\/\/xenonkungen.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/xenonkungen.com\/produkt\/led-a60-40w-1800k-e27-ndsrt-amber-1pf\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/xenonkungen.com\/produkt\/led-a60-40w-1800k-e27-ndsrt-amber-1pf\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/05\/lk-929003627801_MN.jpg\",\"datePublished\":\"2026-05-20T07:51:51+00:00\",\"dateModified\":\"2026-07-07T13:57:00+00:00\",\"description\":\"Philips - LED A60 40W 1800K E27 NDSRT Amber 1PF. Snabb leverans, \u00f6ppet k\u00f6p 30 dagar.\",\"breadcrumb\":{\"@id\":\"https:\/\/xenonkungen.com\/produkt\/led-a60-40w-1800k-e27-ndsrt-amber-1pf\/#breadcrumb\"},\"inLanguage\":\"nb-NO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/xenonkungen.com\/produkt\/led-a60-40w-1800k-e27-ndsrt-amber-1pf\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nb-NO\",\"@id\":\"https:\/\/xenonkungen.com\/produkt\/led-a60-40w-1800k-e27-ndsrt-amber-1pf\/#primaryimage\",\"url\":\"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/05\/lk-929003627801_MN.jpg\",\"contentUrl\":\"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/05\/lk-929003627801_MN.jpg\",\"width\":1200,\"height\":1200,\"caption\":\"IMPORT_LEDKUNGEN\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/xenonkungen.com\/produkt\/led-a60-40w-1800k-e27-ndsrt-amber-1pf\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hem\",\"item\":\"https:\/\/xenonkungen.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/xenonkungen.com\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"LED A60 40W 1800K E27 NDSRT Amber 1PF &#8211; Philips\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/xenonkungen.com\/#website\",\"url\":\"https:\/\/xenonkungen.com\/\",\"name\":\"Xenonkungen\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/xenonkungen.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nb-NO\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Philips LED A60 40W 1800K E27 NDSRT Amber 1PF | Xenon-kongen","description":"Philips - LED A60 40W 1800K E27 NDSRT Amber 1PF. Rask levering, \u00e5pent kj\u00f8p 30 dager.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xenonkungen.com\/no\/produkt\/led-a60-40w-1800k-e27-ndsrt-rav-1pf\/","og_locale":"nb_NO","og_type":"article","og_title":"Philips LED A60 40W 1800K E27 NDSRT Amber 1PF | Xenonkungen","og_description":"Philips - LED A60 40W 1800K E27 NDSRT Amber 1PF. Snabb leverans, \u00f6ppet k\u00f6p 30 dagar.","og_url":"https:\/\/xenonkungen.com\/no\/produkt\/led-a60-40w-1800k-e27-ndsrt-rav-1pf\/","og_site_name":"Xenonkungen","article_modified_time":"2026-07-07T13:57:00+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/05\/lk-929003627801_MN.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/xenonkungen.com\/produkt\/led-a60-40w-1800k-e27-ndsrt-amber-1pf\/","url":"https:\/\/xenonkungen.com\/produkt\/led-a60-40w-1800k-e27-ndsrt-amber-1pf\/","name":"Philips LED A60 40W 1800K E27 NDSRT Amber 1PF | Xenon-kongen","isPartOf":{"@id":"https:\/\/xenonkungen.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/xenonkungen.com\/produkt\/led-a60-40w-1800k-e27-ndsrt-amber-1pf\/#primaryimage"},"image":{"@id":"https:\/\/xenonkungen.com\/produkt\/led-a60-40w-1800k-e27-ndsrt-amber-1pf\/#primaryimage"},"thumbnailUrl":"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/05\/lk-929003627801_MN.jpg","datePublished":"2026-05-20T07:51:51+00:00","dateModified":"2026-07-07T13:57:00+00:00","description":"Philips - LED A60 40W 1800K E27 NDSRT Amber 1PF. Rask levering, \u00e5pent kj\u00f8p 30 dager.","breadcrumb":{"@id":"https:\/\/xenonkungen.com\/produkt\/led-a60-40w-1800k-e27-ndsrt-amber-1pf\/#breadcrumb"},"inLanguage":"nb-NO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xenonkungen.com\/produkt\/led-a60-40w-1800k-e27-ndsrt-amber-1pf\/"]}]},{"@type":"ImageObject","inLanguage":"nb-NO","@id":"https:\/\/xenonkungen.com\/produkt\/led-a60-40w-1800k-e27-ndsrt-amber-1pf\/#primaryimage","url":"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/05\/lk-929003627801_MN.jpg","contentUrl":"https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/05\/lk-929003627801_MN.jpg","width":1200,"height":1200,"caption":"IMPORT_LEDKUNGEN"},{"@type":"BreadcrumbList","@id":"https:\/\/xenonkungen.com\/produkt\/led-a60-40w-1800k-e27-ndsrt-amber-1pf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hem","item":"https:\/\/xenonkungen.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/xenonkungen.com\/shop\/"},{"@type":"ListItem","position":3,"name":"LED A60 40W 1800K E27 NDSRT Amber 1PF &#8211; Philips"}]},{"@type":"WebSite","@id":"https:\/\/xenonkungen.com\/#website","url":"https:\/\/xenonkungen.com\/","name":"Xenonkungen","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xenonkungen.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nb-NO"}]}},"taxonomy_info":{"anvandningsomrade":[{"value":3288,"label":"Hem"}],"product_brand":[{"value":3325,"label":"Philips"}],"product_cat":[{"value":3093,"label":"E27-lampor"}],"pa_farg":[{"value":2244,"label":"Amber"}],"pa_fuktskydd-varde-ipxx":[{"value":1993,"label":"IP20"}],"pa_lampsockel-kontakt":[{"value":3193,"label":"E27"}]},"featured_image_src_large":["https:\/\/xenonkungen.com\/wp-content\/uploads\/2026\/05\/lk-929003627801_MN-1024x1024.jpg",1024,1024,true],"author_info":[],"comment_info":0,"_links":{"self":[{"href":"https:\/\/xenonkungen.com\/no\/wp-json\/wp\/v2\/product\/32524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xenonkungen.com\/no\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/xenonkungen.com\/no\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/xenonkungen.com\/no\/wp-json\/wp\/v2\/comments?post=32524"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xenonkungen.com\/no\/wp-json\/wp\/v2\/media\/32522"}],"wp:attachment":[{"href":"https:\/\/xenonkungen.com\/no\/wp-json\/wp\/v2\/media?parent=32524"}],"wp:term":[{"taxonomy":"anvandningsomrade","embeddable":true,"href":"https:\/\/xenonkungen.com\/no\/wp-json\/wp\/v2\/anvandningsomrade?post=32524"},{"taxonomy":"bilmarken","embeddable":true,"href":"https:\/\/xenonkungen.com\/no\/wp-json\/wp\/v2\/bilmarken?post=32524"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/xenonkungen.com\/no\/wp-json\/wp\/v2\/product_brand?post=32524"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/xenonkungen.com\/no\/wp-json\/wp\/v2\/product_cat?post=32524"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/xenonkungen.com\/no\/wp-json\/wp\/v2\/product_tag?post=32524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}